﻿{"id":11030,"date":"2023-07-11T09:00:00","date_gmt":"2023-07-11T07:00:00","guid":{"rendered":"https:\/\/www.sigterritoires.fr\/?p=11030"},"modified":"2023-07-10T06:55:21","modified_gmt":"2023-07-10T04:55:21","slug":"ferramentas-de-analise-de-rede-qgis-caminho-mais-curto","status":"publish","type":"post","link":"https:\/\/www.sigterritoires.fr\/index.php\/pt\/ferramentas-de-analise-de-rede-qgis-caminho-mais-curto\/","title":{"rendered":"Ferramentas de an\u00e1lise de rede QGis : caminho mais curto"},"content":{"rendered":"\n<p>Tem \u00e0 sua disposi\u00e7\u00e3o dois tipos de ferramentas de <a href=\"https:\/\/www.sigterritoires.fr\/index.php\/pt\/analise-de-rede-com-qgis\/\">an\u00e1lise de rede<\/a>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>c\u00e1lculos do itiner\u00e1rio mais curto ou mais r\u00e1pido<\/li>\n\n\n\n<li>c\u00e1lculo da <a href=\"https:\/\/www.sigterritoires.fr\/index.php\/pt\/ferramentas-de-analise-de-rede-qgis-area-de-servico\/\">\u00e1rea de servi\u00e7o<\/a><\/li>\n<\/ul>\n\n\n\n<p>No \u00e2mbito de uma an\u00e1lise de rede utilizando o QGIS, o itiner\u00e1rio mais curto refere-se ao percurso mais curto entre dois pontos determinados numa rede rodovi\u00e1ria ou de transportes. O objetivo \u00e9 encontrar o itiner\u00e1rio ideal que exija a menor dist\u00e2ncia, tempo ou recursos para viajar de um ponto de partida espec\u00edfico para um ponto final espec\u00edfico.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>A an\u00e1lise do caminho mais curto \u00e9 utilizada para calcular e visualizar o percurso mais eficiente entre dois locais, tendo em conta as restri\u00e7\u00f5es da rede, tais como dist\u00e2ncias, limites de velocidade, ruas de sentido \u00fanico, etc. Esta an\u00e1lise pode ser utilizada em muitas \u00e1reas, como o planeamento de transportes, a log\u00edstica, a otimiza\u00e7\u00e3o de rotas, a navega\u00e7\u00e3o, etc.<\/p>\n\n\n\n<p>No QGIS, existem v\u00e1rios m\u00e9todos para calcular o caminho mais curto, incluindo o <a href=\"https:\/\/docs.qgis.org\/3.28\/fr\/docs\/pyqgis_developer_cookbook\/network_analysis.html\" title=\"algoritmo de Dijkstra\">algoritmo de Dijkstra<\/a> e o algoritmo A* (A-star). Estes algoritmos utilizam dados espaciais, como a rede rodovi\u00e1ria e os atributos das estradas, para determinar o caminho \u00f3timo. A an\u00e1lise do caminho mais curto pode ser efectuada utilizando a ferramenta \u00ab\u00a0An\u00e1lise de rede\u00a0\u00bb ou outras ferramentas espec\u00edficas dispon\u00edveis no QGIS, como o plugin \u00ab\u00a0RoadGraph\u00a0\u00bb.<\/p>\n\n\n\n<p>Para efeitos da an\u00e1lise de rede com o QGIS, uma <strong><em>\u00e1rea de servi\u00e7o<\/em><\/strong> refere-se a uma \u00e1rea geogr\u00e1fica que \u00e9 coberta ou servida por uma rede espec\u00edfica de transporte ou distribui\u00e7\u00e3o. Esta pode incluir elementos como estradas, linhas de transporte p\u00fablico, redes de \u00e1gua ou eletricidade, infra-estruturas de telecomunica\u00e7\u00f5es, etc.<\/p>\n\n\n\n<p>A \u00e1rea de servi\u00e7o representa a extens\u00e3o geogr\u00e1fica a partir da qual os utilizadores podem aceder aos servi\u00e7os ou recursos dispon\u00edveis atrav\u00e9s da rede. Pode ser definida em fun\u00e7\u00e3o de v\u00e1rios crit\u00e9rios, como a dist\u00e2ncia m\u00e1xima, o tempo de desloca\u00e7\u00e3o, a capacidade da rede, etc.<\/p>\n\n\n\n<p>A an\u00e1lise da \u00e1rea de servi\u00e7o no QGIS pode ser utilizada para mapear e analisar as \u00e1reas cobertas por uma rede espec\u00edfica, o que pode ser \u00fatil para tomar decis\u00f5es sobre planeamento, localiza\u00e7\u00e3o de equipamentos, acessibilidade de servi\u00e7os, etc. Esta an\u00e1lise permite visualizar e quantificar o alcance geogr\u00e1fico de uma determinada rede, o que pode facilitar a tomada de decis\u00f5es em muitos dom\u00ednios, como o planeamento urbano, os transportes, o desenvolvimento regional, etc.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">As ferramentas de dist\u00e2ncia mais curta<\/h3>\n\n\n\n<p>Para calcular uma dist\u00e2ncia, precisa de um ou mais pontos de partida e um ou mais pontos de chegada. As ferramentas dispon\u00edveis podem tomar como pontos de partida e de chegada<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>pontos introduzidos manualmente na janela do mapa, designados por \u00ab\u00a0pontos\u00a0\u00bb nos t\u00edtulos das ferramentas, ou<\/li>\n\n\n\n<li>ou uma camada de pontos, designada por \u00ab\u00a0camada\u00a0\u00bb nos t\u00edtulos das ferramentas.<\/li>\n<\/ul>\n\n\n\n<p>Dispomos, portanto, de tr\u00eas ferramentas de caminho mais curto:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><em>Caminho mais curto (da camada ao ponto)<\/em><\/strong>: para cada ponto contido na camada de pontos (pontos de partida), calculamos o caminho mais curto at\u00e9 um ponto introduzido \u00e0 m\u00e3o (ponto de chegada) na janela do mapa;<\/li>\n\n\n\n<li><strong><em>Caminho mais curto (ponto a ponto)<\/em><\/strong>: introduza um primeiro ponto (in\u00edcio) e depois um segundo (fim) na janela do mapa e a ferramenta calcular\u00e1 o caminho mais curto entre os dois;<\/li>\n\n\n\n<li><strong><em>Caminho mais curto (de ponto para camada):<\/em><\/strong> introduza um primeiro ponto (in\u00edcio) na janela do mapa e calcule o caminho mais curto para cada ponto na camada de pontos (fim).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Instrumentos da \u00e1rea de servi\u00e7o.<\/h3>\n\n\n\n<p>Existem duas ferramentas de \u00e1rea de servi\u00e7o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><em>\u00c1rea de servi\u00e7o (da camada):<\/em><\/strong> dada uma dist\u00e2ncia (ou um tempo de viagem), a ferramenta calcula todos os trajectos poss\u00edveis a partir de cada ponto contido na camada de pontos;<\/li>\n\n\n\n<li><strong><em>\u00c1rea de servi\u00e7o (do ponto)<\/em><\/strong>: dada uma dist\u00e2ncia (ou tempo de viagem), a ferramenta calcula todos os trajectos poss\u00edveis a partir de um ponto introduzido na janela do mapa.<\/li>\n<\/ul>\n\n\n\n<p>Veremos um exemplo com pontos inseridos no mapa, pois a utiliza\u00e7\u00e3o de uma camada n\u00e3o altera as op\u00e7\u00f5es poss\u00edveis, apenas o resultado ser\u00e1 a soma de todos os tratamentos ponto-a-ponto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">An\u00e1lise de rede: Caminho mais curto<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"708\" data-attachment-id=\"10978\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/analyse-de-reseau-avec-qgis\/chemin_court\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court.png?fit=1851%2C2046&amp;ssl=1\" data-orig-size=\"1851,2046\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"chemin_court\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court.png?fit=640%2C708&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court.png?resize=640%2C708&#038;ssl=1\" alt=\"par\u00e2metros de processamento do caminho mais curto (ponto a ponto)\" class=\"wp-image-10978\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court.png?resize=926%2C1024&amp;ssl=1 926w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court.png?resize=271%2C300&amp;ssl=1 271w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court.png?resize=768%2C849&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court.png?resize=1390%2C1536&amp;ssl=1 1390w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court.png?resize=136%2C150&amp;ssl=1 136w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court.png?w=1851&amp;ssl=1 1851w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court.png?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">An\u00e1lise de rede: caso mais simples &#8211; defini\u00e7\u00f5es por defeito<\/h3>\n\n\n\n<p>Para executar este processo, basta preencher os primeiros quatro campos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>a camada vetorial com a nossa rede linear<\/li>\n\n\n\n<li>o tipo de caminho a calcular (por defeito, o caminho mais curto)<\/li>\n\n\n\n<li>o ponto de partida<\/li>\n\n\n\n<li>o ponto final<\/li>\n<\/ul>\n\n\n\n<p>Se n\u00e3o tiver outros par\u00e2metros a ter em conta (sentido do tr\u00e2nsito, velocidade autorizada), a execu\u00e7\u00e3o do processo dar-lhe-\u00e1 o percurso pretendido.<\/p>\n\n\n\n<p>Ao clicar no bot\u00e3o \u2026 ao lado dos pontos de partida e de chegada, a janela \u00e9 apagada e aparece uma janela \u2026.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus_court_simple.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"258\" data-attachment-id=\"10984\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-chemin-le-plus-court-danalyse-de-reseau-qgis\/trajet_plus_court_simple\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus_court_simple.png?fit=3838%2C1546&amp;ssl=1\" data-orig-size=\"3838,1546\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"trajet_plus_court_simple\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus_court_simple.png?fit=640%2C258&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus_court_simple.png?resize=640%2C258&#038;ssl=1\" alt=\"resultado do caminho mais curto ponto-a-ponto utilizando a an\u00e1lise de rede QGis com par\u00e2metros por defeito\" class=\"wp-image-10984\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus_court_simple.png?resize=1024%2C412&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus_court_simple.png?resize=300%2C121&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus_court_simple.png?resize=768%2C309&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus_court_simple.png?resize=1536%2C619&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus_court_simple.png?resize=2048%2C825&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus_court_simple.png?resize=150%2C60&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus_court_simple.png?resize=250%2C101&amp;ssl=1 250w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus_court_simple.png?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus_court_simple.png?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<p>Se abrir a tabela de atributos da camada de resultados, ver\u00e1 um atributo <strong><em>cost <\/em><\/strong>que representa a dist\u00e2ncia total do itiner\u00e1rio. Se estiver a trabalhar em coordenadas geogr\u00e1ficas, a dist\u00e2ncia ser\u00e1 em graus.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/table_attributs_chemin_le_plus_court.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"309\" data-attachment-id=\"10986\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-chemin-le-plus-court-danalyse-de-reseau-qgis\/table_attributs_chemin_le_plus_court\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/table_attributs_chemin_le_plus_court.png?fit=1098%2C531&amp;ssl=1\" data-orig-size=\"1098,531\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"table_attributs_chemin_le_plus_court\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/table_attributs_chemin_le_plus_court.png?fit=640%2C309&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/table_attributs_chemin_le_plus_court.png?resize=640%2C309&#038;ssl=1\" alt=\"tabela de atributos do caminho mais curto com o campo de custo que cont\u00e9m a dist\u00e2ncia total\" class=\"wp-image-10986\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/table_attributs_chemin_le_plus_court.png?resize=1024%2C495&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/table_attributs_chemin_le_plus_court.png?resize=300%2C145&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/table_attributs_chemin_le_plus_court.png?resize=768%2C371&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/table_attributs_chemin_le_plus_court.png?resize=150%2C73&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/table_attributs_chemin_le_plus_court.png?resize=250%2C121&amp;ssl=1 250w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/table_attributs_chemin_le_plus_court.png?w=1098&amp;ssl=1 1098w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">An\u00e1lise de rede: casos com tr\u00e1fego num sentido<\/h3>\n\n\n\n<p>Enquanto o primeiro caso se aplica sem problemas a uma viagem em campo aberto, na cidade, a n\u00e3o considera\u00e7\u00e3o dos sentidos de tr\u00e2nsito autorizados conduz frequentemente a resultados in\u00fateis.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_sans_sens_circulation.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" data-attachment-id=\"10988\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-chemin-le-plus-court-danalyse-de-reseau-qgis\/trajet_plus-court_sans_sens_circulation\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_sans_sens_circulation.png?fit=3843%2C2160&amp;ssl=1\" data-orig-size=\"3843,2160\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"trajet_plus-court_sans_sens_circulation\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_sans_sens_circulation.png?fit=640%2C360&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_sans_sens_circulation.png?resize=640%2C360&#038;ssl=1\" alt=\"Resultado do caminho mais curto sem ter em conta a dire\u00e7\u00e3o do tr\u00e1fego\" class=\"wp-image-10988\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_sans_sens_circulation.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_sans_sens_circulation.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_sans_sens_circulation.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_sans_sens_circulation.png?resize=1536%2C863&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_sans_sens_circulation.png?resize=2048%2C1151&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_sans_sens_circulation.png?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_sans_sens_circulation.png?resize=250%2C141&amp;ssl=1 250w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_sans_sens_circulation.png?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_sans_sens_circulation.png?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<p>O itiner\u00e1rio assim calculado segue v\u00e1rias direc\u00e7\u00f5es proibidas. Para ter em conta as direc\u00e7\u00f5es de tr\u00e2nsito, temos o atributo <strong><em>oneway <\/em><\/strong>no OSM. Quando encontramos um valor de <strong>B<\/strong>, isso indica que o tro\u00e7o \u00e9 bidirecional, e quando encontramos um valor de <strong>F<\/strong>, o sentido do tr\u00e1fego \u00e9 o sentido em que o tro\u00e7o foi digitalizado. Um valor de <strong>T<\/strong> indica que o tro\u00e7o n\u00e3o pode ser utilizado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_parametres_sens_circulation.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"823\" data-attachment-id=\"10989\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-chemin-le-plus-court-danalyse-de-reseau-qgis\/chemin_plus_court_parametres_sens_circulation\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_parametres_sens_circulation.png?fit=1623%2C2088&amp;ssl=1\" data-orig-size=\"1623,2088\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"chemin_plus_court_parametres_sens_circulation\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_parametres_sens_circulation.png?fit=640%2C823&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_parametres_sens_circulation.png?resize=640%2C823&#038;ssl=1\" alt=\"parametriza\u00e7\u00e3o do caminho mais curto para utilizar o campo oneway do OSM\" class=\"wp-image-10989\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_parametres_sens_circulation.png?resize=796%2C1024&amp;ssl=1 796w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_parametres_sens_circulation.png?resize=233%2C300&amp;ssl=1 233w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_parametres_sens_circulation.png?resize=768%2C988&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_parametres_sens_circulation.png?resize=1194%2C1536&amp;ssl=1 1194w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_parametres_sens_circulation.png?resize=1592%2C2048&amp;ssl=1 1592w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_parametres_sens_circulation.png?resize=117%2C150&amp;ssl=1 117w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_parametres_sens_circulation.png?w=1623&amp;ssl=1 1623w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_parametres_sens_circulation.png?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<p>Com estes par\u00e2metros, o resultado (a amarelo) \u00e9 coerente e respeita as direc\u00e7\u00f5es do tr\u00e1fego.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_avec_sens_circulation.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" data-attachment-id=\"10990\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-chemin-le-plus-court-danalyse-de-reseau-qgis\/trajet_plus-court_avec_sens_circulation\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_avec_sens_circulation.png?fit=3843%2C2160&amp;ssl=1\" data-orig-size=\"3843,2160\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"trajet_plus-court_avec_sens_circulation\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_avec_sens_circulation.png?fit=640%2C360&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_avec_sens_circulation.png?resize=640%2C360&#038;ssl=1\" alt=\"resultado do caminho mais curto com a dire\u00e7\u00e3o do tr\u00e1fego tomada em considera\u00e7\u00e3o\" class=\"wp-image-10990\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_avec_sens_circulation.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_avec_sens_circulation.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_avec_sens_circulation.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_avec_sens_circulation.png?resize=1536%2C863&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_avec_sens_circulation.png?resize=2048%2C1151&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_avec_sens_circulation.png?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_avec_sens_circulation.png?resize=250%2C141&amp;ssl=1 250w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_avec_sens_circulation.png?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_plus-court_avec_sens_circulation.png?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">An\u00e1lise da rede: caso do trajeto mais r\u00e1pido<\/h3>\n\n\n\n<p>Nos dois exemplos anteriores, escolhemos o <strong><em>tipo de percurso = percurso mais curto<\/em><\/strong>.<\/p>\n\n\n\n<p>Se quisermos ter em conta a velocidade para encontrar o itiner\u00e1rio mais r\u00e1pido, temos duas op\u00e7\u00f5es.<\/p>\n\n\n\n<p>A primeira \u00e9 escolher o tipo de itiner\u00e1rio mais r\u00e1pido e utilizar a velocidade predefinida dos par\u00e2metros da ferramenta do itiner\u00e1rio mais curto.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_vitesse.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"823\" data-attachment-id=\"10992\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-chemin-le-plus-court-danalyse-de-reseau-qgis\/chemin_court-parametre_vitesse\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_vitesse.png?fit=1623%2C2088&amp;ssl=1\" data-orig-size=\"1623,2088\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"chemin_court-parametre_vitesse\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_vitesse.png?fit=640%2C823&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_vitesse.png?resize=640%2C823&#038;ssl=1\" alt=\"defini\u00e7\u00e3o do caminho mais curto com dire\u00e7\u00e3o de tr\u00e1fego e velocidade predefinidas\" class=\"wp-image-10992\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_vitesse.png?resize=796%2C1024&amp;ssl=1 796w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_vitesse.png?resize=233%2C300&amp;ssl=1 233w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_vitesse.png?resize=768%2C988&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_vitesse.png?resize=1194%2C1536&amp;ssl=1 1194w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_vitesse.png?resize=1592%2C2048&amp;ssl=1 1592w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_vitesse.png?resize=117%2C150&amp;ssl=1 117w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_vitesse.png?w=1623&amp;ssl=1 1623w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_vitesse.png?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<p>A ferramenta utiliza este par\u00e2metro assim que o itiner\u00e1rio mais r\u00e1pido \u00e9 solicitado <span style=\"text-decoration: underline;\">E n\u00e3o \u00e9 introduzido nenhum campo de velocidade.<\/span><\/p>\n\n\n\n<p>O itiner\u00e1rio calculado ser\u00e1 o mesmo que quando \u00e9 pedido o itiner\u00e1rio mais curto; o que muda \u00e9 o atributo <strong><em>cost <\/em><\/strong>do resultado, que ser\u00e1 expresso em horas e n\u00e3o em metros.<\/p>\n\n\n\n<p>Para ter em conta as velocidades autorizadas contidas nas camadas OSM, \u00e9 necess\u00e1rio preencher o campo Velocidade, seleccionando o atributo <strong><em>maxspeed<\/em><\/strong>. Tenha o cuidado de apresentar as etiquetas com as velocidades dos tro\u00e7os, pois o atributo nem sempre est\u00e1 preenchido. Neste caso, <strong><em>maxspeed <\/em><\/strong>tem o valor 0. Se pedir o percurso mais r\u00e1pido,<span style=\"text-decoration: underline;\"> os tro\u00e7os com este valor ser\u00e3o considerados inutiliz\u00e1veis<\/span> e o resultado ser\u00e1 distorcido ou imposs\u00edvel.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_maxspeed.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"559\" data-attachment-id=\"10993\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-chemin-le-plus-court-danalyse-de-reseau-qgis\/chemin_court-parametre_maxspeed\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_maxspeed.png?fit=2073%2C1812&amp;ssl=1\" data-orig-size=\"2073,1812\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"chemin_court-parametre_maxspeed\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_maxspeed.png?fit=640%2C559&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_maxspeed.png?resize=640%2C559&#038;ssl=1\" alt=\"defini\u00e7\u00e3o da velocidade m\u00e1xima no caminho mais curto\" class=\"wp-image-10993\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_maxspeed.png?resize=1024%2C895&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_maxspeed.png?resize=300%2C262&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_maxspeed.png?resize=768%2C671&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_maxspeed.png?resize=1536%2C1343&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_maxspeed.png?resize=2048%2C1790&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_maxspeed.png?resize=150%2C131&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_maxspeed.png?resize=172%2C150&amp;ssl=1 172w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_maxspeed.png?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_court-parametre_maxspeed.png?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<p>O exemplo seguinte calcula o itiner\u00e1rio mais curto sem ter em conta as velocidades autorizadas (a vermelho) e o itiner\u00e1rio mais r\u00e1pido tendo-as em conta (a amarelo).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_le_plus_rapide.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" data-attachment-id=\"10994\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-chemin-le-plus-court-danalyse-de-reseau-qgis\/trajet_le_plus_rapide\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_le_plus_rapide.png?fit=3843%2C2160&amp;ssl=1\" data-orig-size=\"3843,2160\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"trajet_le_plus_rapide\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_le_plus_rapide.png?fit=640%2C360&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_le_plus_rapide.png?resize=640%2C360&#038;ssl=1\" alt=\"percurso mais curto e percurso mais r\u00e1pido tendo em conta a velocidade m\u00e1xima do OSM\" class=\"wp-image-10994\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_le_plus_rapide.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_le_plus_rapide.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_le_plus_rapide.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_le_plus_rapide.png?resize=1536%2C863&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_le_plus_rapide.png?resize=2048%2C1151&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_le_plus_rapide.png?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_le_plus_rapide.png?resize=250%2C141&amp;ssl=1 250w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_le_plus_rapide.png?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_le_plus_rapide.png?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">An\u00e1lise de rede: Procurar um caminho de um ponto para uma camada<\/h3>\n\n\n\n<p>Vejamos agora o caso em que pretendemos encontrar o hospital mais pr\u00f3ximo. Neste exemplo, temos um ponto de partida que introduzimos manualmente e temos a camada OSM com um filtro para mostrar apenas hospitais.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_point_couche.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" data-attachment-id=\"10997\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-chemin-le-plus-court-danalyse-de-reseau-qgis\/chemin_plus_court_point_couche\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_point_couche.png?fit=3843%2C2160&amp;ssl=1\" data-orig-size=\"3843,2160\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"chemin_plus_court_point_couche\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_point_couche.png?fit=640%2C360&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_point_couche.png?resize=640%2C360&#038;ssl=1\" alt=\"dados para a procura de trajectos de um ponto para uma camada de pontos\" class=\"wp-image-10997\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_point_couche.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_point_couche.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_point_couche.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_point_couche.png?resize=1536%2C863&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_point_couche.png?resize=2048%2C1151&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_point_couche.png?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_point_couche.png?resize=250%2C141&amp;ssl=1 250w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_point_couche.png?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/chemin_plus_court_point_couche.png?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<p>Abrimos o processo do <strong><em>caminho mais curto (do ponto para a camada)<\/em><\/strong> e simplesmente indicamos qual a camada que cont\u00e9m os pontos de chegada e introduzimos o nosso ponto de partida <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_couche_vers_point.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"558\" data-attachment-id=\"10998\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-chemin-le-plus-court-danalyse-de-reseau-qgis\/parametres_couche_vers_point\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_couche_vers_point.png?fit=2076%2C1809&amp;ssl=1\" data-orig-size=\"2076,1809\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"parametres_couche_vers_point\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_couche_vers_point.png?fit=640%2C558&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_couche_vers_point.png?resize=640%2C558&#038;ssl=1\" alt=\"par\u00e2metros para encontrar o caminho mais curto de um ponto para uma camada\" class=\"wp-image-10998\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_couche_vers_point.png?resize=1024%2C892&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_couche_vers_point.png?resize=300%2C261&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_couche_vers_point.png?resize=768%2C669&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_couche_vers_point.png?resize=1536%2C1338&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_couche_vers_point.png?resize=2048%2C1785&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_couche_vers_point.png?resize=150%2C131&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_couche_vers_point.png?resize=172%2C150&amp;ssl=1 172w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_couche_vers_point.png?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_couche_vers_point.png?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<p>e a ferramenta calcular\u00e1 o caminho mais curto entre o nosso ponto de partida e cada um dos pontos na camada de destino.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_chemin_point_vers_couche.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"344\" data-attachment-id=\"10999\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-chemin-le-plus-court-danalyse-de-reseau-qgis\/resultat_chemin_point_vers_couche\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_chemin_point_vers_couche.png?fit=3807%2C2046&amp;ssl=1\" data-orig-size=\"3807,2046\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"resultat_chemin_point_vers_couche\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_chemin_point_vers_couche.png?fit=640%2C344&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_chemin_point_vers_couche.png?resize=640%2C344&#038;ssl=1\" alt=\"resultado do caminho mais curto de um ponto para uma camada\" class=\"wp-image-10999\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_chemin_point_vers_couche.png?resize=1024%2C550&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_chemin_point_vers_couche.png?resize=300%2C161&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_chemin_point_vers_couche.png?resize=768%2C413&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_chemin_point_vers_couche.png?resize=1536%2C825&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_chemin_point_vers_couche.png?resize=2048%2C1101&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_chemin_point_vers_couche.png?resize=150%2C81&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_chemin_point_vers_couche.png?resize=250%2C134&amp;ssl=1 250w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_chemin_point_vers_couche.png?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_chemin_point_vers_couche.png?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<p>Como a camada Hospitais cont\u00e9m 78 entidades, temos 78 trajectos calculados. Se abrirmos a tabela de atributos e ordenarmos o campo <strong><em>cost <\/em><\/strong>do menor para o maior, temos as rotas ordenadas por comprimento.<\/p>\n\n\n\n<p>O hospital mais pr\u00f3ximo \u00e9 o de id 4356718789, a 44,987 km do nosso ponto de partida. Naturalmente, todas as op\u00e7\u00f5es que vimos nos exemplos ponto-a-ponto (dire\u00e7\u00e3o do tr\u00e1fego, limite de velocidade) podem ser utilizadas com a ferramenta ponto-a-camada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tem \u00e0 sua disposi\u00e7\u00e3o dois tipos de ferramentas de an\u00e1lise de rede: No \u00e2mbito de uma an\u00e1lise de rede utilizando o QGIS, o itiner\u00e1rio mais curto refere-se ao percurso mais curto entre dois pontos determinados numa&hellip;<\/p>\n","protected":false},"author":1,"featured_media":10994,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2134],"tags":[2309,2311,2347,2313,2315,2317,2319,2321,2158,2160,2323,2325],"class_list":["post-11030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-qgis","tag-analise-de-rede","tag-analysis-pt","tag-caminho-mais-curto","tag-network-pt","tag-ogr2pgsql-pt","tag-osm-pt","tag-osm2pgrouting-pt","tag-pbf-pt","tag-postgis-pt","tag-qgis-pt","tag-shp-pt","tag-simbologia-pt"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/trajet_le_plus_rapide.png?fit=3843%2C2160&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p6XU0A-2RU","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/11030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/comments?post=11030"}],"version-history":[{"count":0,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/11030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/media\/10994"}],"wp:attachment":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/media?parent=11030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/categories?post=11030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/tags?post=11030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}