﻿{"id":11044,"date":"2023-07-13T09:00:00","date_gmt":"2023-07-13T07:00:00","guid":{"rendered":"https:\/\/www.sigterritoires.fr\/?p=11044"},"modified":"2023-07-11T18:46:55","modified_gmt":"2023-07-11T16:46:55","slug":"herramientas-de-analisis-de-redes-qgisarea-de-servicio","status":"publish","type":"post","link":"https:\/\/www.sigterritoires.fr\/index.php\/es\/herramientas-de-analisis-de-redes-qgisarea-de-servicio\/","title":{"rendered":"Herramientas de an\u00e1lisis de redes QGis:\u00e1rea de servicio"},"content":{"rendered":"\n<p>A efectos del an\u00e1lisis de redes con QGIS, por \u00e1rea de servicio se entiende una zona geogr\u00e1fica cubierta o servida por una red espec\u00edfica de transporte o distribuci\u00f3n. Puede incluir elementos como carreteras, l\u00edneas de transporte p\u00fablico, redes de agua o electricidad, infraestructuras de telecomunicaciones, etc.<\/p>\n\n\n\n<p>La zona de servicio representa la extensi\u00f3n geogr\u00e1fica a partir de la cual los usuarios pueden acceder a los servicios o recursos disponibles a trav\u00e9s de la red. Puede definirse en funci\u00f3n de diversos criterios, como la distancia m\u00e1xima, la duraci\u00f3n del trayecto, la capacidad de la red, etc.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\">\u00c1rea de servicio (de un punto)<\/h2>\n\n\n\n<p>Si abre la herramienta <strong><em>\u00c1rea de servicio (de un punto)<\/em><\/strong>, encontrar\u00e1 una ventana de configuraci\u00f3n similar a las del <strong><em>camino m\u00e1s corto<\/em><\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_simple.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"692\" data-attachment-id=\"11007\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-danalyse-de-reseau-qgiszone-de-desserte\/parametres_zone_de_deserte_simple\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_simple.png?fit=1872%2C2025&amp;ssl=1\" data-orig-size=\"1872,2025\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"parametres_zone_de_deserte_simple\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_simple.png?fit=640%2C692&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_simple.png?resize=640%2C692&#038;ssl=1\" alt=\"par\u00e1metros por defecto de la herramienta \u00e1rea de servicio (para el punto)\" class=\"wp-image-11007\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_simple.png?resize=947%2C1024&amp;ssl=1 947w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_simple.png?resize=277%2C300&amp;ssl=1 277w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_simple.png?resize=768%2C831&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_simple.png?resize=1420%2C1536&amp;ssl=1 1420w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_simple.png?resize=139%2C150&amp;ssl=1 139w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_simple.png?w=1872&amp;ssl=1 1872w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_simple.png?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<p>La diferencia est\u00e1 en el campo <strong><em>Costo del viaje<\/em><\/strong>. En este campo, introduciremos<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>o bien la distancia m\u00e1xima de nuestra zona de servicio, desde el punto de partida, en unidades de mapa,<\/li>\n\n\n\n<li>o bien el tiempo m\u00e1ximo de viaje desde el punto de partida, en horas.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c1rea de servicio: caso m\u00e1s sencillo<\/h3>\n\n\n\n<p>Si dejamos las opciones por defecto, la herramienta calcula el \u00e1rea de servicio (en color malva) calculando todas las rutas posibles, de 2 km cada una, desde nuestro punto de partida.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_simple.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" data-attachment-id=\"11008\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-danalyse-de-reseau-qgiszone-de-desserte\/resultat_zone_de_desserte_simple\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_simple.png?fit=3843%2C2160&amp;ssl=1\" data-orig-size=\"3843,2160\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"resultat_zone_de_desserte_simple\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_simple.png?fit=640%2C360&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_simple.png?resize=640%2C360&#038;ssl=1\" alt=\"resultado del \u00e1rea de servicio con par\u00e1metros por defecto\" class=\"wp-image-11008\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_simple.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_simple.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_simple.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_simple.png?resize=1536%2C863&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_simple.png?resize=2048%2C1151&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_simple.png?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_simple.png?resize=250%2C141&amp;ssl=1 250w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_simple.png?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_simple.png?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Zona de servicio: sentidos de circulaci\u00f3n tenidos en cuenta<\/h3>\n\n\n\n<p>Estas distancias te\u00f3ricas no tienen en cuenta las direcciones prohibidas. Para ello, vamos a hacer lo mismo que hicimos para las rutas m\u00e1s cortas, configurando un campo de direcci\u00f3n. Para tener en cuenta las direcciones de tr\u00e1fico, tenemos el atributo <strong><em>oneway <\/em><\/strong>en OSM. Cuando encontramos un valor de <strong>B<\/strong>, indica que el tramo es de doble sentido, y cuando encontramos un valor de <strong>F<\/strong>, el sentido del tr\u00e1fico es el sentido en el que est\u00e1 digitalizado el tramo. Un valor <strong>T<\/strong> indica que el tramo no puede ser utilizado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"11009\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-danalyse-de-reseau-qgiszone-de-desserte\/parametres_zone_de_deserte_avec_sens\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens.png?fit=2076%2C1812&amp;ssl=1\" data-orig-size=\"2076,1812\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"parametres_zone_de_deserte_avec_sens\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens.png?fit=640%2C559&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens.png?resize=640%2C558&#038;ssl=1\" alt=\"par\u00e1metros del \u00e1rea de servicio (punto) configurados para tener en cuenta las direcciones del tr\u00e1fico\" class=\"wp-image-11009\" width=\"640\" height=\"558\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens.png?resize=1024%2C894&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens.png?resize=300%2C262&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens.png?resize=768%2C670&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens.png?resize=1536%2C1341&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens.png?resize=2048%2C1788&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens.png?resize=150%2C131&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens.png?resize=172%2C150&amp;ssl=1 172w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens.png?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens.png?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<p>El resultado (en amarillo) muestra que la zona de captaci\u00f3n es inferior a la calculada.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway-1.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" data-attachment-id=\"11011\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-danalyse-de-reseau-qgiszone-de-desserte\/resultat_zone_de_desserte_oneway-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway-1.png?fit=3843%2C2160&amp;ssl=1\" data-orig-size=\"3843,2160\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"resultat_zone_de_desserte_oneway-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway-1.png?fit=640%2C360&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway-1.png?resize=640%2C360&#038;ssl=1\" alt=\"resultado del \u00e1rea de servicio teniendo en cuenta los sentidos de circulaci\u00f3n\" class=\"wp-image-11011\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway-1.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway-1.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway-1.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway-1.png?resize=1536%2C863&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway-1.png?resize=2048%2C1151&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway-1.png?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway-1.png?resize=250%2C141&amp;ssl=1 250w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway-1.png?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway-1.png?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<p>Pero en esta zona urbana, la mayor\u00eda de las carreteras tienen un l\u00edmite de velocidad de 45 km\/h, mientras que otras tienen un l\u00edmite de 60 km\/h.<\/p>\n\n\n\n<p>A 45 km\/h nuestros 2 km se recorren en 2 minutos 40 segundos. Si el factor limitante en nuestra \u00e1rea de servicio es el tiempo, podemos modificar los par\u00e1metros para encontrar todas las rutas que se pueden cubrir en 2m40s (0,044333 horas). Para ello, configuramos el campo <strong><em>velocidad<\/em><\/strong> para que utilice el atributo <a href=\"https:\/\/wiki.openstreetmap.org\/wiki\/Key:maxspeed\" title=\"maxspeed de OSM\"><strong><em>maxspeed <\/em><\/strong>de OSM<\/a> y cambiamos el tipo de trayecto a calcular por <strong><em>El m\u00e1s r\u00e1pido<\/em><\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens_et_maxspeed.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"559\" data-attachment-id=\"11012\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-danalyse-de-reseau-qgiszone-de-desserte\/parametres_zone_de_deserte_avec_sens_et_maxspeed\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens_et_maxspeed.png?fit=2076%2C1812&amp;ssl=1\" data-orig-size=\"2076,1812\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"parametres_zone_de_deserte_avec_sens_et_maxspeed\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens_et_maxspeed.png?fit=640%2C559&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens_et_maxspeed.png?resize=640%2C559&#038;ssl=1\" alt=\"par\u00e1metros del \u00e1rea de servicio (del punto) para tener en cuenta los sentidos de circulaci\u00f3n y el l\u00edmite de velocidad\" class=\"wp-image-11012\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens_et_maxspeed.png?resize=1024%2C894&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens_et_maxspeed.png?resize=300%2C262&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens_et_maxspeed.png?resize=768%2C670&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens_et_maxspeed.png?resize=1536%2C1341&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens_et_maxspeed.png?resize=2048%2C1788&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens_et_maxspeed.png?resize=150%2C131&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens_et_maxspeed.png?resize=172%2C150&amp;ssl=1 172w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens_et_maxspeed.png?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/parametres_zone_de_deserte_avec_sens_et_maxspeed.png?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<p>El resultado es un \u00e1rea de servicio (en rojo) mayor que la calculada utilizando s\u00f3lo las indicaciones de tr\u00e1fico, ya que utilizando las rutas m\u00e1s r\u00e1pidas se puede viajar m\u00e1s lejos manteniendo el mismo tiempo de viaje.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway_et_maxspeed.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" data-attachment-id=\"11013\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/les-outils-danalyse-de-reseau-qgiszone-de-desserte\/resultat_zone_de_desserte_oneway_et_maxspeed\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway_et_maxspeed.png?fit=3843%2C2160&amp;ssl=1\" data-orig-size=\"3843,2160\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"resultat_zone_de_desserte_oneway_et_maxspeed\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway_et_maxspeed.png?fit=640%2C360&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway_et_maxspeed.png?resize=640%2C360&#038;ssl=1\" alt=\"resultado del \u00e1rea de servicio (del punto) teniendo en cuenta los sentidos de circulaci\u00f3n y las velocidades m\u00e1ximas autorizadas\" class=\"wp-image-11013\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway_et_maxspeed.png?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway_et_maxspeed.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway_et_maxspeed.png?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway_et_maxspeed.png?resize=1536%2C863&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway_et_maxspeed.png?resize=2048%2C1151&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway_et_maxspeed.png?resize=150%2C84&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway_et_maxspeed.png?resize=250%2C141&amp;ssl=1 250w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway_et_maxspeed.png?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_oneway_et_maxspeed.png?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<p>La otra herramienta disponible, <strong><em>\u00c1rea de servicio (de la capa)<\/em><\/strong>, realiza los mismos c\u00e1lculos pero para cada punto contenido en la capa. El resultado es un \u00e1rea de servicio por punto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A efectos del an\u00e1lisis de redes con QGIS, por \u00e1rea de servicio se entiende una zona geogr\u00e1fica cubierta o servida por una red espec\u00edfica de transporte o distribuci\u00f3n. Puede incluir elementos como carreteras, l\u00edneas de transporte&hellip;<\/p>\n","protected":false},"author":1,"featured_media":11008,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1357],"tags":[2394,2295,2400,2297,1369,2396,2398],"class_list":["post-11044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-qgis-es","tag-analisis","tag-analysis-es","tag-area-de-servicio","tag-network-es","tag-qgis-es","tag-red","tag-trajecto"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2023\/06\/resultat_zone_de_desserte_simple.png?fit=3843%2C2160&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p6XU0A-2S8","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/11044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/comments?post=11044"}],"version-history":[{"count":0,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/11044\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/media\/11008"}],"wp:attachment":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/media?parent=11044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/categories?post=11044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/tags?post=11044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}