﻿{"id":13794,"date":"2025-05-22T10:00:00","date_gmt":"2025-05-22T08:00:00","guid":{"rendered":"https:\/\/www.sigterritoires.fr\/?p=13794"},"modified":"2025-05-19T23:08:28","modified_gmt":"2025-05-19T21:08:28","slug":"tutorial-leaflet-sesion-6","status":"publish","type":"post","link":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/","title":{"rendered":"Tutorial Leaflet: sesi\u00f3n 6"},"content":{"rendered":"<div class=\"ead-preview\"><div class=\"ead-document\" style=\"position: relative;padding-top: 90%\"><div class=\"ead-iframe-wrapper\"><iframe src=\"\/\/docs.google.com\/viewer?url=https%3A%2F%2Fwww.sigterritoires.fr%2Fwp-content%2Fuploads%2F2025%2F05%2FInitiation-a-leaflet-seance-6es.pptx&amp;embedded=true&amp;hl=en\" title=\"Document embarqu\u00e9\" class=\"ead-iframe\" style=\"width: 100%;height: 100%;border: none;position: absolute;left: 0;top: 0;visibility: hidden;\"><\/iframe><\/div>\t\t\t<div class=\"ead-document-loading\" style=\"width:100%;height:100%;position:absolute;left:0;top:0;z-index:10\">\n\t\t\t\t<div class=\"ead-loading-wrap\">\n\t\t\t\t\t<div class=\"ead-loading-main\">\n\t\t\t\t\t\t<div class=\"ead-loading\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.sigterritoires.fr\/wp-content\/plugins\/embed-any-document\/images\/loading.svg\" width=\"55\" height=\"55\" alt=\"Chargeur\">\n\t\t\t\t\t\t\t<span>En cours de chargement&hellip;<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"ead-loading-foot\">\n\t\t\t\t\t\t<div class=\"ead-loading-foot-title\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.sigterritoires.fr\/wp-content\/plugins\/embed-any-document\/images\/EAD-logo.svg\" alt=\"Logo EAD\" width=\"36\" height=\"23\"\/>\n\t\t\t\t\t\t\t<span>Cela prend trop de temps\u00a0?<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<div class=\"ead-document-btn ead-reload-btn\" role=\"button\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.sigterritoires.fr\/wp-content\/plugins\/embed-any-document\/images\/reload.svg\" alt=\"Recharger\" width=\"12\" height=\"12\"\/> Recharger le document\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<span>|<\/span>\n\t\t\t\t\t\t\t<a href=\"https:\/\/docs.google.com\/viewer?url=https%3A%2F%2Fwww.sigterritoires.fr%2Fwp-content%2Fuploads%2F2025%2F05%2FInitiation-a-leaflet-seance-6es.pptx&#038;hl=en\" class=\"ead-document-btn\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.sigterritoires.fr\/wp-content\/plugins\/embed-any-document\/images\/open.svg\" alt=\"Ouvert\" width=\"12\" height=\"12\"\/> Ouvrir dans un nouvel onglet\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenu <\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><ul class='ez-toc-list-level-2' ><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Objetivos_de_la_sesion_Creacion_de_un_miniproyecto_cartografico\" >Objetivos de la sesi\u00f3n: Creaci\u00f3n de un miniproyecto cartogr\u00e1fico<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Objetivos_de_aprendizaje\" >Objetivos de aprendizaje<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Temas_sugeridos_para_los_miniproyectos\" >Temas sugeridos para los miniproyectos<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#1_Mapa_de_rutas_de_senderismo\" >1. Mapa de rutas de senderismo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#2_Mapa_turistico_de_un_pueblo\" >2. Mapa tur\u00edstico de un pueblo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#3_Mapa_de_localizacion_de_los_servicios_publicos\" >3. Mapa de localizaci\u00f3n de los servicios p\u00fablicos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Resultados_esperados\" >Resultados esperados<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Presentacion_de_GitHub_Pages\" >Presentaci\u00f3n de GitHub Pages<\/a><ul class='ez-toc-list-level-2' ><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Pasos_para_utilizar_GitHub_Pages\" >Pasos para utilizar GitHub Pages :<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#1_Crear_un_repositorio_en_GitHub\" >1. Crear un repositorio en GitHub<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#2_Sube_o_empuja_tu_codigo_al_repositorio\" >2. Sube o empuja tu c\u00f3digo al repositorio<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Metodo_1_Subir_archivos_manualmente\" >M\u00e9todo 1: Subir archivos manualmente<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Metodo_2_Empuja_tu_codigo_desde_Git\" >M\u00e9todo 2: Empuja tu c\u00f3digo desde Git<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#3_Ve_a_la_configuracion_del_repositorio_y_activa_GitHub_Pages_en_la_seccion_%C2%ABPages%C2%BB\" >3. Ve a la configuraci\u00f3n del repositorio y activa GitHub Pages en la secci\u00f3n \u00abPages\u00bb.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#4_Tu_sitio_sera_accesible_a_traves_de_la_URL_generada\" >4. Tu sitio ser\u00e1 accesible a trav\u00e9s de la URL generada<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Consejos_adicionales\" >Consejos adicionales:<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Presentacion_de_Netlify\" >Presentaci\u00f3n de Netlify<\/a><ul class='ez-toc-list-level-2' ><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Pasos_para_utilizar_Netlify\" >Pasos para utilizar Netlify :<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Crear_una_cuenta_Netlify\" >Crear una cuenta Netlify<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Conecta_tu_repositorio_GitHub\" >Conecta tu repositorio GitHub<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Seleccione_el_proyecto_a_desplegar\" >Seleccione el proyecto a desplegar<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Netlify_desplegara_automaticamente_su_sitio_y_generara_una_URL_unica\" >Netlify desplegar\u00e1 autom\u00e1ticamente su sitio y generar\u00e1 una URL \u00fanica<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Consejos_adicionales-2\" >Consejos adicionales:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Ventajas_de_Netlify_para_alojar_tu_mapa_Leaflet\" >Ventajas de Netlify para alojar tu mapa Leaflet:<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#Presente_su_proyecto_de_folleto\" >Presente su proyecto de folleto<\/a><ul class='ez-toc-list-level-2' ><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#%C2%BFComo_hacerlo\" >\u00bfC\u00f3mo hacerlo?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Objetivos_de_la_sesion_Creacion_de_un_miniproyecto_cartografico\"><\/span>Objetivos de la sesi\u00f3n: Creaci\u00f3n de un miniproyecto cartogr\u00e1fico<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo de esta sesi\u00f3n es utilizar todos los conocimientos adquiridos en el curso de introducci\u00f3n a Leaflet para crear un mapa interactivo completo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los alumnos eligen un tema entre varias propuestas de miniproyectos y aplican los conceptos t\u00e9cnicos y metodol\u00f3gicos tratados en las sesiones anteriores.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Objetivos_de_aprendizaje\"><\/span>Objetivos de aprendizaje<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dise\u00f1ar un mapa web interactivo coherente<\/li>\n\n\n\n<li>Organizar datos geogr\u00e1ficos (puntos, l\u00edneas, pol\u00edgonos)<\/li>\n\n\n\n<li>Manejar eventos e interactividad (clics, hovers, filtros, etc.)<\/li>\n\n\n\n<li>Integrar una interfaz de usuario (men\u00fas, filtros, leyendas, etc.)<\/li>\n\n\n\n<li>Publicar el mapa en un entorno local o en l\u00ednea<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Temas_sugeridos_para_los_miniproyectos\"><\/span>Temas sugeridos para los miniproyectos<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_Mapa_de_rutas_de_senderismo\"><\/span>1. Mapa de rutas de senderismo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Objetivo: crear un mapa que muestre una o varias rutas de senderismo.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contenido posible :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Trazados de senderos GPX\/GeoJSON<\/li>\n\n\n\n<li>Puntos de inter\u00e9s: puntos de partida, miradores, merenderos, etc.<\/li>\n\n\n\n<li>Pop-ups ilustrados (texto + im\u00e1genes)<\/li>\n\n\n\n<li>Carta del senderista (popup o enlace)<\/li>\n\n\n\n<li>Minimapa o escala<\/li>\n\n\n\n<li>Bot\u00f3n de zoom en la ruta<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Conocimientos necesarios :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Visualizaci\u00f3n de l\u00edneas y puntos<\/li>\n\n\n\n<li>Utilizaci\u00f3n de estilos personalizados<\/li>\n\n\n\n<li>Adici\u00f3n de iconos e im\u00e1genes<\/li>\n\n\n\n<li>Controles de leaflet (escala, minimapa, control de capas)<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_Mapa_turistico_de_un_pueblo\"><\/span>2. Mapa tur\u00edstico de un pueblo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Objetivo: crear un mapa interactivo para los visitantes.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contenido posible :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Monumentos, museos, alojamientos, restaurantes<\/li>\n\n\n\n<li>Filtros por categor\u00eda (alojamiento \/ cultura \/ naturaleza, etc.)<\/li>\n\n\n\n<li>Descripciones y horarios de apertura en ventanas emergentes<\/li>\n\n\n\n<li>A\u00f1adir un mapa tem\u00e1tico de fondo (por ejemplo, OpenStreetMap Humanitario, Topo, etc.)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Habilidades utilizadas :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Grupos de capas y capas filtrables<\/li>\n\n\n\n<li>Ventanas emergentes din\u00e1micas<\/li>\n\n\n\n<li>Integraci\u00f3n de iconos personalizados<\/li>\n\n\n\n<li>Control de leyendas y men\u00fas HTML interactivos<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Mapa_de_localizacion_de_los_servicios_publicos\"><\/span>3. Mapa de localizaci\u00f3n de los servicios p\u00fablicos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Objetivo: crear un mapa \u00fatil para residentes o visitantes.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contenido posible:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ubicaci\u00f3n de colegios, hospitales, ayuntamientos, oficinas de correos, comisar\u00edas, etc.<\/li>\n\n\n\n<li>Consultas sencillas: mostrar escuelas en un radio de X km<\/li>\n\n\n\n<li>Rutas o enlaces a Google Maps<\/li>\n\n\n\n<li>Mostrar horarios o contactos<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Competencias requeridas:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gesti\u00f3n de datos ad hoc<\/li>\n\n\n\n<li>Reacciones a eventos (clic en una categor\u00eda \u2192 actualizaci\u00f3n del mapa)<\/li>\n\n\n\n<li>Ventanas emergentes mejoradas<\/li>\n\n\n\n<li>Adici\u00f3n de men\u00fas desplegables<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Resultados_esperados\"><\/span>Resultados esperados<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un mapa interactivo funcional compuesto por :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Un mapa de fondo y capas de datos geogr\u00e1ficos<\/li>\n\n\n\n<li>Una o varias formas de interacci\u00f3n (clics, men\u00fas, filtros, etc.)<\/li>\n\n\n\n<li>Un dise\u00f1o limpio, legible y atractivo<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Este mapa puede publicarse en un repositorio de GitHub o integrarse en un sitio personal o blog.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h1 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Presentacion_de_GitHub_Pages\"><\/span>Presentaci\u00f3n de GitHub Pages<span class=\"ez-toc-section-end\"><\/span><\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">GitHub Pages es un servicio de alojamiento gratuito que te permite publicar un sitio web est\u00e1tico directamente desde un repositorio de GitHub. Es especialmente \u00fatil para alojar proyectos personales, portafolios o proyectos como mapas interactivos creados con Leaflet. Este servicio es perfecto para peque\u00f1os proyectos web en los que necesitas publicar r\u00e1pidamente una versi\u00f3n online sin tener que preocuparte de configurar un servidor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Pasos_para_utilizar_GitHub_Pages\"><\/span>Pasos para utilizar GitHub Pages :<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_Crear_un_repositorio_en_GitHub\"><\/span>1. Crear un repositorio en GitHub<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfQu\u00e9 es un repositorio GitHub?\n<ul class=\"wp-block-list\">\n<li>Un repositorio GitHub es donde almacenas todos los archivos relacionados con tu proyecto. Esto incluye archivos HTML, CSS y JavaScript, as\u00ed como recursos como im\u00e1genes y archivos de datos.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>C\u00f3mo crear un repositorio ?\n<ul class=\"wp-block-list\">\n<li>Con\u00e9ctate a tu cuenta de GitHub.Haz clic en el bot\u00f3n \u00abNuevo\u00bb o \u00abCrear un nuevo repositorio\u00bb.Ponle un nombre a tu repositorio (por ejemplo, mi-leaflet-map).Si es necesario, a\u00f1ade una descripci\u00f3n de tu proyecto.Aseg\u00farate de que el repositorio es p\u00fablico para poder hacerlo accesible en l\u00ednea.<\/li>\n\n\n\n<li>Una vez creado el repositorio, GitHub te proporcionar\u00e1 una URL del repositorio (por ejemplo, https:\/\/github.com\/francpoisatilio\/cartes-leaflet).<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_Sube_o_empuja_tu_codigo_al_repositorio\"><\/span>2. Sube o empuja tu c\u00f3digo al repositorio<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que tu repositorio ha sido creado, necesitas a\u00f1adir los archivos de tu proyecto a \u00e9l. Hay varios m\u00e9todos para hacerlo, dependiendo de tus preferencias.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Metodo_1_Subir_archivos_manualmente\"><\/span>M\u00e9todo 1: Subir archivos manualmente<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Haz clic en el bot\u00f3n \u00abA\u00f1adir archivo\u00bb en tu repositorio de GitHub, luego selecciona \u00abSubir archivos\u00bb.<\/li>\n\n\n\n<li>Arrastra y suelta tus archivos (HTML, CSS, JavaScript, im\u00e1genes, etc.) en la ventana de subida.<\/li>\n\n\n\n<li>Haz clic en \u00abConfirmar cambios\u00bb para guardar los archivos en tu repositorio.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Metodo_2_Empuja_tu_codigo_desde_Git\"><\/span>M\u00e9todo 2: Empuja tu c\u00f3digo desde Git<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Si trabajas localmente con Git, puedes insertar los archivos directamente en el repositorio con los siguientes comandos :<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\"><code>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/code><code>git init<\/code><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\"><code>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/code><code>git add .<\/code><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\"><code>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/code><code>git commit -m \"Initial commit\"<\/code><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\"><code>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/code><code>git remote add origin https:\/\/github.com\/username\/ma-carte-leaflet.git<\/code><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\"><code>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/code><code>git push -u origin master<\/code><\/pre>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Ve_a_la_configuracion_del_repositorio_y_activa_GitHub_Pages_en_la_seccion_%C2%ABPages%C2%BB\"><\/span>3. Ve a la configuraci\u00f3n del repositorio y activa GitHub Pages en la secci\u00f3n \u00abPages\u00bb.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Una vez subidos los archivos de tu proyecto al repositorio, tienes que activar GitHub Pages para publicar el sitio online.<\/li>\n\n\n\n<li>Pasos:\n<ul class=\"wp-block-list\">\n<li>Abre tu repositorio en GitHub.Ve a la pesta\u00f1a \u00abConfiguraci\u00f3n\u00bb del repositorio.En el men\u00fa lateral, despl\u00e1zate hasta la secci\u00f3n \u00abGitHub Pages\u00bb.Bajo el encabezado \u00abFuente\u00bb, elige la rama desde la que quieres alojar el sitio. Por lo general, se utiliza la rama \u00abmain\u00bb o \u00abmaster\u00bb.<\/li>\n\n\n\n<li>Haz clic en el bot\u00f3n \u00abGuardar\u00bb para activar GitHub Pages.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, GitHub generar\u00e1 una URL \u00fanica para tu sitio web, con el siguiente aspecto<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>https:&#47;&#47;username.github.io\/ma-carte-leaflet\/<\/code><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">Esta URL ser\u00e1 la direcci\u00f3n p\u00fablica en la que se podr\u00e1 acceder a tu mapa de Leaflet.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"4_Tu_sitio_sera_accesible_a_traves_de_la_URL_generada\"><\/span>4. Tu sitio ser\u00e1 accesible a trav\u00e9s de la URL generada<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>URL p\u00fablica: Una vez que hayas activado GitHub Pages, la URL generada ser\u00e1 la siguiente:\n<ul class=\"wp-block-list\">\n<li>https:\/\/username.github.io\/mi-tarjeta-hoja\/<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Es importante tener en cuenta que la p\u00e1gina puede tardar unos minutos en generarse. A continuaci\u00f3n, puede acceder a su tarjeta Leaflet abriendo esta URL en un navegador.<\/li>\n\n\n\n<li>Si quieres personalizar el nombre de dominio de tu sitio, GitHub te permite utilizar un nombre de dominio personalizado (por ejemplo, www.macarteleaflet.com) a\u00f1adiendo un archivo CNAME a tu repositorio.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Consejos_adicionales\"><\/span>Consejos adicionales:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Verificaci\u00f3n<\/strong>: Antes de hacer p\u00fablico tu sitio, aseg\u00farate de que todos los archivos necesarios est\u00e1n correctamente incluidos en tu repositorio, incluidos los archivos de mapas, recursos JavaScript (Leaflet, etc.) y archivos CSS.<\/li>\n\n\n\n<li><strong>Repositorio privado<\/strong>: Si tienes un repositorio privado y deseas utilizar GitHub Pages, ten en cuenta que esta opci\u00f3n s\u00f3lo est\u00e1 disponible para usuarios de pago. Sin embargo, para proyectos p\u00fablicos sencillos, la versi\u00f3n gratuita de GitHub Pages funciona perfectamente.<\/li>\n\n\n\n<li><strong>Soluci\u00f3n de problemas<\/strong>: Si tu mapa no se muestra correctamente, comprueba que todos los archivos est\u00e1n enlazados correctamente y que los enlaces a recursos externos (por ejemplo, Leaflet CDN) son v\u00e1lidos.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Con estos pasos, puede poner en l\u00ednea f\u00e1cilmente sus mapas interactivos creados con Leaflet. Esto proporciona una forma r\u00e1pida y sencilla de compartir sus proyectos con otros usuarios, o incluso de desplegarlos en un servidor personal.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h1 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Presentacion_de_Netlify\"><\/span>Presentaci\u00f3n de Netlify<span class=\"ez-toc-section-end\"><\/span><\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Netlify es una plataforma de alojamiento r\u00e1pida y moderna para sitios web est\u00e1ticos. Facilita el despliegue, la gesti\u00f3n y el alojamiento de sitios web, con despliegue automatizado desde un repositorio Git (GitHub, GitLab, Bitbucket). Netlify destaca por su facilidad de uso, su integraci\u00f3n continua y sus m\u00faltiples funcionalidades como la gesti\u00f3n de redirecciones, formularios y nombres de dominio personalizados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con Netlify, puedes desplegar sitios web est\u00e1ticos (como mapas Leaflet), aplicaciones modernas y otros proyectos en tan solo unos clics. Tambi\u00e9n ofrece servicios gratuitos de CDN (Content Delivery Network), SSL y optimizaci\u00f3n del rendimiento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Pasos_para_utilizar_Netlify\"><\/span>Pasos para utilizar Netlify :<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Crear_una_cuenta_Netlify\"><\/span>Crear una cuenta Netlify<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfQu\u00e9 es una cuenta Netlify?<br>Una cuenta Netlify te permitir\u00e1 gestionar tus despliegues de sitios web est\u00e1ticos. Puedes registrarte con tu direcci\u00f3n de correo electr\u00f3nico, o m\u00e1s f\u00e1cilmente utilizando tu cuenta de GitHub, GitLab o Bitbucket.<\/li>\n\n\n\n<li>Pasos para crear una cuenta:\n<ul class=\"wp-block-list\">\n<li>Ve a Netlify.<\/li>\n\n\n\n<li>Haz clic en \u00ab\u00a0Reg\u00edstrate\u00a0\u00bb.<\/li>\n\n\n\n<li>Elige un m\u00e9todo de registro (correo electr\u00f3nico o a trav\u00e9s de GitHub).<\/li>\n\n\n\n<li>Sigue las instrucciones para configurar tu cuenta.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conecta_tu_repositorio_GitHub\"><\/span>Conecta tu repositorio GitHub<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conexi\u00f3n a GitHub:<br>Una vez que hayas creado tu cuenta de Netlify, necesitas conectar Netlify a tu repositorio de GitHub donde se encuentra el c\u00f3digo de tu proyecto (el mapa de Leaflet).<\/li>\n\n\n\n<li>Pasos para conectar GitHub a Netlify:\n<ul class=\"wp-block-list\">\n<li>Ve a tu panel de Netlify.<\/li>\n\n\n\n<li>Haz clic en \u00ab\u00a0Nuevo sitio desde Git\u00a0\u00bb.Elige GitHub como fuente.Netlify te pedir\u00e1 que permitas el acceso a tu cuenta de GitHub, lo que le permitir\u00e1 recuperar tus repositorios.<\/li>\n\n\n\n<li>Selecciona el repositorio de GitHub que contiene tu proyecto Leaflet (por ejemplo, my-leaflet-map).<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Seleccione_el_proyecto_a_desplegar\"><\/span>Seleccione el proyecto a desplegar<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Selecci\u00f3n del proyecto:<br>Despu\u00e9s de conectar tu cuenta de GitHub a Netlify, Netlify mostrar\u00e1 todos tus repositorios de GitHub. Seleccione el repositorio que contiene el c\u00f3digo para su proyecto de mapa.<\/li>\n\n\n\n<li>Configurar los ajustes del proyecto:\n<ul class=\"wp-block-list\">\n<li>Netlify le pedir\u00e1 que configure los ajustes de despliegue (por ejemplo, qu\u00e9 rama desplegar, normalmente main o master).Si tiene archivos particulares que generar o compilar antes del despliegue (por ejemplo, si est\u00e1 utilizando un generador de sitios est\u00e1ticos como Jekyll o Hugo), puede especificar comandos de compilaci\u00f3n. Para un proyecto Leaflet sencillo, no necesita ninguna configuraci\u00f3n adicional.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Haga clic en \u00ab\u00a0Desplegar sitio\u00a0\u00bb para iniciar el despliegue.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Netlify_desplegara_automaticamente_su_sitio_y_generara_una_URL_unica\"><\/span>Netlify desplegar\u00e1 autom\u00e1ticamente su sitio y generar\u00e1 una URL \u00fanica<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Despliegue autom\u00e1tico:<br>Despu\u00e9s de seleccionar el repositorio y configurar los ajustes, Netlify inicia el proceso de despliegue. El sitio se construye y publica autom\u00e1ticamente.<\/li>\n\n\n\n<li>URL generada:<br>Una vez completado el despliegue, Netlify generar\u00e1 una URL \u00fanica para acceder a su mapa en l\u00ednea. La URL ser\u00e1 t\u00edpicamente de la forma<\/li>\n<\/ul>\n\n\n\n<pre class=\"wp-block-code\"><code>https:&#47;&#47;nombre-del-proyecto.netlify.app\/<\/code><\/pre>\n\n\n\n<pre class=\"wp-block-code\"><code>Ejemplo: Si su proyecto se llama mi-mapa-leaflet, la URL podr\u00eda ser:\nhttps:&#47;&#47;mi-mapa-leaflet.netlify.app\/<\/code><\/pre>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Consejos_adicionales-2\"><\/span>Consejos adicionales:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cambia la URL del sitio<\/strong>: Si quieres utilizar un nombre de dominio personalizado (por ejemplo, www.macarteleaflet.com), puedes configurarlo f\u00e1cilmente en el panel de Netlify a\u00f1adiendo un dominio personalizado y configurando DNS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Controla las actualizaciones<\/strong>: Netlify ofrece un sistema de despliegue continuo, lo que significa que tan pronto como empujes cambios a tu repositorio de GitHub, el sitio se actualizar\u00e1 autom\u00e1ticamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Monitorizaci\u00f3n del rendimiento<\/strong>: Netlify tambi\u00e9n ofrece herramientas para monitorizar el rendimiento de tu sitio (tiempo de carga, disponibilidad, etc.).<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ventajas_de_Netlify_para_alojar_tu_mapa_Leaflet\"><\/span>Ventajas de Netlify para alojar tu mapa Leaflet:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Despliegue r\u00e1pido y sencillo: Publica tu mapa en tan solo unos clics.<\/li>\n\n\n\n<li>Alojamiento CDN: Netlify pone a tu disposici\u00f3n una infraestructura CDN que optimiza la velocidad de carga de tus p\u00e1ginas.<\/li>\n\n\n\n<li>SSL gratuito : Cada sitio desplegado en Netlify se beneficia autom\u00e1ticamente de un certificado SSL (HTTPS).<\/li>\n\n\n\n<li>Soporte para sitios est\u00e1ticos: Perfecto para alojar mapas Leaflet y otros proyectos web est\u00e1ticos.<\/li>\n\n\n\n<li>Despliegue continuo: Automatiza el proceso de actualizaci\u00f3n de tu sitio tan pronto como subas nuevos cambios a GitHub.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Con estos pasos, puedes subir r\u00e1pidamente tu mapa Leaflet a Netlify y compartirlo f\u00e1cilmente con otros. Es una gran manera de alojar proyectos de mapas interactivos, sin tener que gestionar servidores complejos.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Presente_su_proyecto_de_folleto\"><\/span>Presente su proyecto de folleto<span class=\"ez-toc-section-end\"><\/span><\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">En esta sesi\u00f3n final, habr\u00e1 realizado un proyecto individual que incorpore los principales elementos estudiados (capas, estilos, interacciones, controles, etc.).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Te invitamos a compartir tu proyecto con nosotros, para que podamos darte un feedback personalizado y, si lo deseas, incluirlo entre los ejemplos que aparecer\u00e1n en nuestras futuras publicaciones.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_hacerlo\"><\/span>\u00bfC\u00f3mo hacerlo?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Publique su proyecto (c\u00f3digo y mapa) en GitHub o en un servicio equivalente y env\u00edenos el enlace a su repositorio a trav\u00e9s del formulario que encontrar\u00e1 a continuaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los proyectos se examinar\u00e1n de acuerdo con los siguientes criterios:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Buen uso de la API de Leaflet<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Legibilidad y organizaci\u00f3n del c\u00f3digo<\/li>\n\n\n\n<li>Calidad visual y funcional del mapa<\/li>\n\n\n\n<li>Pertinencia del tema y de los datos elegidos<\/li>\n\n\n\n<li>Rellene el siguiente formulario. Recibir\u00e1 una respuesta personalizada en unos d\u00edas.<\/li>\n<\/ul>\n\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f13335-o1\" lang=\"fr-FR\" dir=\"ltr\" data-wpcf7-id=\"13335\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/posts\/13794#wpcf7-f13335-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulaire de contact\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"13335\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"fr_FR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f13335-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label>Su nombre<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><br \/>\n<\/label>\n<\/p>\n<p><label>Su e-mail<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><br \/>\n<\/label>\n<\/p>\n<p><label>Enlace al repositorio GitHub<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-github-url\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-url wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-url\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"https:\/\/github.com\/su-nombre\/projet-leaflet\" value=\"\" type=\"url\" name=\"your-github-url\" \/><\/span><br \/>\n<\/label>\n<\/p>\n<p><label>Su mensaje (facultativo)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span><br \/>\n<\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"90\"\/><script data-jetpack-boost=\"ignore\">\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Objetivos de la sesi\u00f3n: Creaci\u00f3n de un miniproyecto cartogr\u00e1fico El objetivo de esta sesi\u00f3n es utilizar todos los conocimientos adquiridos en el curso de introducci\u00f3n a Leaflet para crear un mapa interactivo completo. Los alumnos eligen&hellip;<\/p>\n","protected":false},"author":1,"featured_media":13806,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3018],"tags":[3164,2939,3166,3168,2032],"class_list":["post-13794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-webmapping-es","tag-github-es","tag-leaflet-es","tag-mini-project-es","tag-netlify-es","tag-tutorial"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Objetivos de la sesi\u00f3n: Creaci\u00f3n de un miniproyecto cartogr\u00e1fico El objetivo de esta sesi\u00f3n es utilizar todos los conocimientos adquiridos en el curso de introducci\u00f3n a Leaflet para crear un mapa interactivo completo. Los alumnos eligen un tema entre varias propuestas de miniproyectos y aplican los conceptos t\u00e9cnicos y metodol\u00f3gicos tratados en las sesiones anteriores.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Atilio Francois\"\/>\n\t<meta name=\"google-site-verification\" content=\"ByXHZUbGNn7RNv-Xk5A-ysTZrM65VLIO2RxfSJ2nIEQ\" \/>\n\t<meta name=\"keywords\" content=\"github,leaflet,mini-project,netlify,tutorial\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Blog SIG &amp; Territoires | le portail des professionnels du SIG\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Tutorial Leaflet: sesi\u00f3n 6 | Blog SIG &amp; Territoires\" \/>\n\t\t<meta property=\"og:description\" content=\"Objetivos de la sesi\u00f3n: Creaci\u00f3n de un miniproyecto cartogr\u00e1fico El objetivo de esta sesi\u00f3n es utilizar todos los conocimientos adquiridos en el curso de introducci\u00f3n a Leaflet para crear un mapa interactivo completo. Los alumnos eligen un tema entre varias propuestas de miniproyectos y aplican los conceptos t\u00e9cnicos y metodol\u00f3gicos tratados en las sesiones anteriores.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-05-22T08:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-05-19T21:08:28+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/atilio.francois\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@SigTerritoires\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Tutorial Leaflet: sesi\u00f3n 6 | Blog SIG &amp; Territoires\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Objetivos de la sesi\u00f3n: Creaci\u00f3n de un miniproyecto cartogr\u00e1fico El objetivo de esta sesi\u00f3n es utilizar todos los conocimientos adquiridos en el curso de introducci\u00f3n a Leaflet para crear un mapa interactivo completo. Los alumnos eligen un tema entre varias propuestas de miniproyectos y aplican los conceptos t\u00e9cnicos y metodol\u00f3gicos tratados en las sesiones anteriores.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@SigTerritoires\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/tutorial-leaflet-sesion-6\\\/#article\",\"name\":\"Tutorial Leaflet: sesi\\u00f3n 6 | Blog SIG & Territoires\",\"headline\":\"Tutorial Leaflet: sesi\\u00f3n 6\",\"author\":{\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.sigterritoires.fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/seance-6es.jpg?fit=1280%2C720&ssl=1\",\"width\":1280,\"height\":720},\"datePublished\":\"2025-05-22T10:00:00+02:00\",\"dateModified\":\"2025-05-19T23:08:28+02:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/tutorial-leaflet-sesion-6\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/tutorial-leaflet-sesion-6\\\/#webpage\"},\"articleSection\":\"webmapping, github, leaflet, mini-project, netlify, tutorial, Espa\\u00f1ol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/tutorial-leaflet-sesion-6\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sigterritoires.fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/category\\\/webmapping-es\\\/#listItem\",\"name\":\"webmapping\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/category\\\/webmapping-es\\\/#listItem\",\"position\":2,\"name\":\"webmapping\",\"item\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/category\\\/webmapping-es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/tutorial-leaflet-sesion-6\\\/#listItem\",\"name\":\"Tutorial Leaflet: sesi\\u00f3n 6\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/tutorial-leaflet-sesion-6\\\/#listItem\",\"position\":3,\"name\":\"Tutorial Leaflet: sesi\\u00f3n 6\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/category\\\/webmapping-es\\\/#listItem\",\"name\":\"webmapping\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/#person\",\"name\":\"Atilio Francois\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/tutorial-leaflet-sesion-6\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f76dc2a720162999bce81d6c99b6d7b9517d6600ad7ceb5ed5268f02cefaa0ee?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Atilio Francois\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/author\\\/admin\\\/\",\"name\":\"Atilio Francois\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/tutorial-leaflet-sesion-6\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f76dc2a720162999bce81d6c99b6d7b9517d6600ad7ceb5ed5268f02cefaa0ee?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Atilio Francois\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/tutorial-leaflet-sesion-6\\\/#webpage\",\"url\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/tutorial-leaflet-sesion-6\\\/\",\"name\":\"Tutorial Leaflet: sesi\\u00f3n 6 | Blog SIG & Territoires\",\"description\":\"Objetivos de la sesi\\u00f3n: Creaci\\u00f3n de un miniproyecto cartogr\\u00e1fico El objetivo de esta sesi\\u00f3n es utilizar todos los conocimientos adquiridos en el curso de introducci\\u00f3n a Leaflet para crear un mapa interactivo completo. Los alumnos eligen un tema entre varias propuestas de miniproyectos y aplican los conceptos t\\u00e9cnicos y metodol\\u00f3gicos tratados en las sesiones anteriores.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/tutorial-leaflet-sesion-6\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.sigterritoires.fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/seance-6es.jpg?fit=1280%2C720&ssl=1\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/tutorial-leaflet-sesion-6\\\/#mainImage\",\"width\":1280,\"height\":720},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/index.php\\\/es\\\/tutorial-leaflet-sesion-6\\\/#mainImage\"},\"datePublished\":\"2025-05-22T10:00:00+02:00\",\"dateModified\":\"2025-05-19T23:08:28+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.sigterritoires.fr\\\/\",\"name\":\"Blog SIG & Territoires\",\"description\":\"le portail des professionnels du SIG\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sigterritoires.fr\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Tutorial Leaflet: sesi\u00f3n 6 | Blog SIG & Territoires","description":"Objetivos de la sesi\u00f3n: Creaci\u00f3n de un miniproyecto cartogr\u00e1fico El objetivo de esta sesi\u00f3n es utilizar todos los conocimientos adquiridos en el curso de introducci\u00f3n a Leaflet para crear un mapa interactivo completo. Los alumnos eligen un tema entre varias propuestas de miniproyectos y aplican los conceptos t\u00e9cnicos y metodol\u00f3gicos tratados en las sesiones anteriores.","canonical_url":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/","robots":"max-image-preview:large","keywords":"github,leaflet,mini-project,netlify,tutorial","webmasterTools":{"google-site-verification":"ByXHZUbGNn7RNv-Xk5A-ysTZrM65VLIO2RxfSJ2nIEQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#article","name":"Tutorial Leaflet: sesi\u00f3n 6 | Blog SIG & Territoires","headline":"Tutorial Leaflet: sesi\u00f3n 6","author":{"@id":"https:\/\/www.sigterritoires.fr\/index.php\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.sigterritoires.fr\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2025\/05\/seance-6es.jpg?fit=1280%2C720&ssl=1","width":1280,"height":720},"datePublished":"2025-05-22T10:00:00+02:00","dateModified":"2025-05-19T23:08:28+02:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#webpage"},"isPartOf":{"@id":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#webpage"},"articleSection":"webmapping, github, leaflet, mini-project, netlify, tutorial, Espa\u00f1ol"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.sigterritoires.fr#listItem","position":1,"name":"Home","item":"https:\/\/www.sigterritoires.fr","nextItem":{"@type":"ListItem","@id":"https:\/\/www.sigterritoires.fr\/index.php\/es\/category\/webmapping-es\/#listItem","name":"webmapping"}},{"@type":"ListItem","@id":"https:\/\/www.sigterritoires.fr\/index.php\/es\/category\/webmapping-es\/#listItem","position":2,"name":"webmapping","item":"https:\/\/www.sigterritoires.fr\/index.php\/es\/category\/webmapping-es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#listItem","name":"Tutorial Leaflet: sesi\u00f3n 6"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.sigterritoires.fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#listItem","position":3,"name":"Tutorial Leaflet: sesi\u00f3n 6","previousItem":{"@type":"ListItem","@id":"https:\/\/www.sigterritoires.fr\/index.php\/es\/category\/webmapping-es\/#listItem","name":"webmapping"}}]},{"@type":"Person","@id":"https:\/\/www.sigterritoires.fr\/#person","name":"Atilio Francois","image":{"@type":"ImageObject","@id":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/f76dc2a720162999bce81d6c99b6d7b9517d6600ad7ceb5ed5268f02cefaa0ee?s=96&d=mm&r=g","width":96,"height":96,"caption":"Atilio Francois"}},{"@type":"Person","@id":"https:\/\/www.sigterritoires.fr\/index.php\/author\/admin\/#author","url":"https:\/\/www.sigterritoires.fr\/index.php\/author\/admin\/","name":"Atilio Francois","image":{"@type":"ImageObject","@id":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f76dc2a720162999bce81d6c99b6d7b9517d6600ad7ceb5ed5268f02cefaa0ee?s=96&d=mm&r=g","width":96,"height":96,"caption":"Atilio Francois"}},{"@type":"WebPage","@id":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#webpage","url":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/","name":"Tutorial Leaflet: sesi\u00f3n 6 | Blog SIG & Territoires","description":"Objetivos de la sesi\u00f3n: Creaci\u00f3n de un miniproyecto cartogr\u00e1fico El objetivo de esta sesi\u00f3n es utilizar todos los conocimientos adquiridos en el curso de introducci\u00f3n a Leaflet para crear un mapa interactivo completo. Los alumnos eligen un tema entre varias propuestas de miniproyectos y aplican los conceptos t\u00e9cnicos y metodol\u00f3gicos tratados en las sesiones anteriores.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/www.sigterritoires.fr\/#website"},"breadcrumb":{"@id":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#breadcrumblist"},"author":{"@id":"https:\/\/www.sigterritoires.fr\/index.php\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.sigterritoires.fr\/index.php\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2025\/05\/seance-6es.jpg?fit=1280%2C720&ssl=1","@id":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#mainImage","width":1280,"height":720},"primaryImageOfPage":{"@id":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/#mainImage"},"datePublished":"2025-05-22T10:00:00+02:00","dateModified":"2025-05-19T23:08:28+02:00"},{"@type":"WebSite","@id":"https:\/\/www.sigterritoires.fr\/#website","url":"https:\/\/www.sigterritoires.fr\/","name":"Blog SIG & Territoires","description":"le portail des professionnels du SIG","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/www.sigterritoires.fr\/#person"}}]},"og:locale":"fr_FR","og:site_name":"Blog SIG &amp; Territoires | le portail des professionnels du SIG","og:type":"article","og:title":"Tutorial Leaflet: sesi\u00f3n 6 | Blog SIG &amp; Territoires","og:description":"Objetivos de la sesi\u00f3n: Creaci\u00f3n de un miniproyecto cartogr\u00e1fico El objetivo de esta sesi\u00f3n es utilizar todos los conocimientos adquiridos en el curso de introducci\u00f3n a Leaflet para crear un mapa interactivo completo. Los alumnos eligen un tema entre varias propuestas de miniproyectos y aplican los conceptos t\u00e9cnicos y metodol\u00f3gicos tratados en las sesiones anteriores.","og:url":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/","article:published_time":"2025-05-22T08:00:00+00:00","article:modified_time":"2025-05-19T21:08:28+00:00","article:publisher":"https:\/\/www.facebook.com\/atilio.francois\/","twitter:card":"summary","twitter:site":"@SigTerritoires","twitter:title":"Tutorial Leaflet: sesi\u00f3n 6 | Blog SIG &amp; Territoires","twitter:description":"Objetivos de la sesi\u00f3n: Creaci\u00f3n de un miniproyecto cartogr\u00e1fico El objetivo de esta sesi\u00f3n es utilizar todos los conocimientos adquiridos en el curso de introducci\u00f3n a Leaflet para crear un mapa interactivo completo. Los alumnos eligen un tema entre varias propuestas de miniproyectos y aplican los conceptos t\u00e9cnicos y metodol\u00f3gicos tratados en las sesiones anteriores.","twitter:creator":"@SigTerritoires"},"aioseo_meta_data":{"post_id":"13794","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-05-11 17:48:48","updated":"2025-06-04 17:23:44","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.sigterritoires.fr\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/category\/webmapping-es\/\" title=\"webmapping\">webmapping<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTutorial Leaflet: sesi\u00f3n 6\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.sigterritoires.fr"},{"label":"webmapping","link":"https:\/\/www.sigterritoires.fr\/index.php\/es\/category\/webmapping-es\/"},{"label":"Tutorial Leaflet: sesi\u00f3n 6","link":"https:\/\/www.sigterritoires.fr\/index.php\/es\/tutorial-leaflet-sesion-6\/"}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2025\/05\/seance-6es.jpg?fit=1280%2C720&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p6XU0A-3Au","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/13794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/comments?post=13794"}],"version-history":[{"count":0,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/13794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/media\/13806"}],"wp:attachment":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/media?parent=13794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/categories?post=13794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/tags?post=13794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}