﻿{"id":2861,"date":"2015-12-03T15:05:55","date_gmt":"2015-12-03T14:05:55","guid":{"rendered":"http:\/\/www.sigterritoires.fr\/?p=2861"},"modified":"2015-12-03T15:05:55","modified_gmt":"2015-12-03T14:05:55","slug":"exporter-un-document-arcmap-mxd-vers-google-earth-kmz","status":"publish","type":"post","link":"https:\/\/www.sigterritoires.fr\/index.php\/exporter-un-document-arcmap-mxd-vers-google-earth-kmz\/","title":{"rendered":"Exporter un document ArcMap (mxd) vers Google Earth (kmz)"},"content":{"rendered":"<p>Vous connaissez s\u00fbrement le moyen d&rsquo;exporter une couche ArcMap en kml ou kmz pour les afficher dans Google Earth.<br \/>\nMais, saviez-vous qu&rsquo;il est possible d&rsquo;exporter directement une carte enti\u00e8re?<\/p>\n<p>Voici comment faire.<!--more--><\/p>\n<p>L&rsquo;outil est disponible dans la toolbox et ne n\u00e9cessite que du fichier mxd en entr\u00e9e et de l&#8217;emplacement et du nom que vous souhaitez pour le fichier kmz.<\/p>\n<p>Vous pouvez donc l&rsquo;utiliser tel quel sur n&rsquo;importe quel projet ArcMap. Par contre il vaut mieux \u00ab\u00a0nettoyer\u00a0\u00bb un peu votre document.<\/p>\n<p>Vous devez faire attention \u00e0 deux choses:<\/p>\n<p>La premi\u00e8re : puisque vous allez superposer vos couches du document sur Google Earth, il n&rsquo;est pas utile d&rsquo;afficher les couches qui peuvent \u00eatre avantageusement remplac\u00e9es par l&rsquo;affichage de Google Earth. Par exemple, la couche \u00ab\u00a0Terre\u00a0\u00bb. Si vous la gardez activ\u00e9e dans votre document, elle se superposera(et cachera) l&rsquo;image de la terre de Google Earth. De plus, \u00e7a augmente la taille du fichier kmz et par cons\u00e9quent le temps de chargement dans Google Earth.<\/p>\n<p>La deuxi\u00e8me : les tables attributaires sont converties au format kmz, de mani\u00e8re \u00e0 afficher les attributs lorsque vous cliquez sur une entit\u00e9 dans Google Earth. Pensez \u00e0 ne laissez affichables que les attributs qui vous int\u00e9ressent, sous peine aussi d&rsquo;augmenter la taille du fichier kmz et ralentir son chargement.<\/p>\n<p>Voici la vid\u00e9o avec la d\u00e9marche \u00e0 suivre:<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-2861-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2015\/12\/mxd2kmz.mp4?_=1\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2015\/12\/mxd2kmz.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2015\/12\/mxd2kmz.mp4<\/a><\/video><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous connaissez s\u00fbrement le moyen d&rsquo;exporter une couche ArcMap en kml ou kmz pour les afficher dans Google Earth. Mais, saviez-vous qu&rsquo;il est possible d&rsquo;exporter directement une carte enti\u00e8re? Voici comment faire.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[145,146,147,26],"tags":[15,65,306,202,32,305,300],"class_list":["post-2861","post","type-post","status-publish","format-standard","hentry","category-arcgis","category-arcmap","category-images","category-outils-et-methodes","tag-arcgis","tag-arcmap","tag-document","tag-export","tag-google-earth","tag-kmz","tag-mxd"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p6XU0A-K9","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/2861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2861"}],"version-history":[{"count":0,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/2861\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}