﻿{"id":4896,"date":"2018-02-27T11:43:49","date_gmt":"2018-02-27T10:43:49","guid":{"rendered":"http:\/\/www.sigterritoires.fr\/?p=4896"},"modified":"2018-11-30T08:23:34","modified_gmt":"2018-11-30T07:23:34","slug":"qgis-3-0-est-disponible","status":"publish","type":"post","link":"https:\/\/www.sigterritoires.fr\/index.php\/qgis-3-0-est-disponible\/","title":{"rendered":"QGis 3.0 est disponible"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/qgis3_1.png\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4897\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/qgis-3-0-est-disponible\/qgis3_1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/qgis3_1.png?fit=606%2C293&amp;ssl=1\" data-orig-size=\"606,293\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"qgis3_1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/qgis3_1.png?fit=606%2C293&amp;ssl=1\" class=\"aligncenter size-full wp-image-4897\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/qgis3_1.png?resize=606%2C293\" alt=\"QGis 3.0 splash screen\" width=\"606\" height=\"293\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/qgis3_1.png?w=606&amp;ssl=1 606w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/qgis3_1.png?resize=300%2C145&amp;ssl=1 300w\" sizes=\"auto, (max-width: 606px) 100vw, 606px\" \/><\/a>La nouvelle version de QGis est disponible depuis le 23 f\u00e9vrier 2018.<\/p>\n<p>Petit rappel des raisons de cette nouvelle mouture:<!--more--><\/p>\n<ul>\n<li>Deux nouvelles versions majeures des biblioth\u00e8ques de base Qt et Python sont sorties. L\u2019ancienne version Qt4 (la base de QGIS) ne sera plus support\u00e9e par les nouveaux syst\u00e8mes d\u2019exploitation, en particulier Mac OS X. Ce passage \u00e0 Qt5 et Python 3 aura \u00e9t\u00e9 un sacr\u00e9 challenge pour le projet QGIS et ses d\u00e9veloppeurs.<\/li>\n<li>L\u2019API de QGIS a \u00e9t\u00e9 remani\u00e9e, de fa\u00e7on \u00e0 impl\u00e9menter diff\u00e9rentes classes et m\u00e9thodes de fa\u00e7on plus \u00e9l\u00e9gante. De ce fait, de nouvelles classes on \u00e9t\u00e9 n\u00e9cessaires et les anciennes seront d\u00e9pr\u00e9ci\u00e9es.<\/li>\n<li>L\u2019utilisation de Qt5 am\u00e8ne beaucoup de nouvelles possibilit\u00e9s et de fonctionnalit\u00e9s : fonctions graphiques, widgets QML, graphiques et bien plus encore.<\/li>\n<li>Les terminaux mobiles seront bien mieux support\u00e9s par Qt5.<\/li>\n<\/ul>\n<p>Mais comme tout cela est bien th\u00e9orique, je vous propose quelques vid\u00e9os glan\u00e9es sur le site de North Road pour voir du concret (et vous donner envie de t\u00e9l\u00e9charger la nouvelle version).<\/p>\n<p>18 petites vid\u00e9os avec des nouveaut\u00e9s, juste pour donner un avant-go\u00fbt.<\/p>\n<h5>De nouveaux outils de saisie de formes en utilisant les styles de DAO:<\/h5>\n<div style=\"width: 638px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-1\" width=\"638\" height=\"410\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/Cad_style.mp4?_=1\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/Cad_style.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/Cad_style.mp4<\/a><\/video><\/div>\n<h5>\u00c9dition interactive des \u00e9tiquettes dans les projets:<\/h5>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-2\" width=\"640\" height=\"468\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/edition_labels.mp4?_=2\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/edition_labels.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/edition_labels.mp4<\/a><\/video><\/div>\n<h5>\u00c9dition interactive des couleurs\u00a0 d&rsquo;un raster de style valeurs uniques:<\/h5>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-3\" width=\"640\" height=\"328\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/edition_style.mp4?_=3\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/edition_style.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/edition_style.mp4<\/a><\/video><\/div>\n<h5>Le Gestionnaire des sources de donn\u00e9es vous permet de charger facilement tout type de donn\u00e9es:<\/h5>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-4\" width=\"640\" height=\"497\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/gestionnaire_donnees.mp4?_=4\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/gestionnaire_donnees.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/gestionnaire_donnees.mp4<\/a><\/video><\/div>\n<h5><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">Int\u00e9gration compl\u00e8te du support de GeoPackage:<br \/>\n<\/span><\/span><\/h5>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-5\" width=\"640\" height=\"475\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/geopackage.mp4?_=5\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/geopackage.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/geopackage.mp4<\/a><\/video><\/div>\n<h5><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">D\u00e9finissez les styles des annotations de votre carte en utilisant une combinaison\u00a0 de symboles <\/span><\/span><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">de remplissage <\/span><\/span><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">et d&rsquo;effets de couleurs:<\/span><\/span><\/h5>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-6\" width=\"640\" height=\"466\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/annotations.mp4?_=6\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/annotations.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/annotations.mp4<\/a><\/video><\/div>\n<h5>Disponibilit\u00e9 de nombreux traitements nouveaux:<\/h5>\n<div style=\"width: 434px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-7\" width=\"434\" height=\"492\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/traitements.mp4?_=7\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/traitements.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/traitements.mp4<\/a><\/video><\/div>\n<h5>Affichage des donn\u00e9es avec un multi-fen\u00eatrage li\u00e9:<\/h5>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-8\" width=\"640\" height=\"478\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/multifenetrage.mp4?_=8\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/multifenetrage.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/multifenetrage.mp4<\/a><\/video><\/div>\n<h5><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">Valeurs par d\u00e9faut plus intelligentes pour les widgets de l&rsquo;\u00e9diteur lors du chargement de couches, y compris les cases \u00e0 cocher, les widgets de date et autres:<\/span><\/span><\/h5>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-9\" width=\"640\" height=\"545\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/default.mp4?_=9\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/default.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/default.mp4<\/a><\/video><\/div>\n<h5><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\">Pr\u00e9visualisation des limites valides des projections cartographiques, pour valider facilement vos choix de SRC:<\/span><\/h5>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-10\" width=\"640\" height=\"587\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/previewSRC.mp4?_=10\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/previewSRC.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/previewSRC.mp4<\/a><\/video><\/div>\n<h5><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">Ex\u00e9cuter des t\u00e2ches complexes en arri\u00e8re-plan, sans bloquer votre flux de travail:<\/span><\/span><\/h5>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-11\" width=\"640\" height=\"457\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/background.mp4?_=11\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/background.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/background.mp4<\/a><\/video><\/div>\n<h5><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">Prise en charge compl\u00e8te des fichiers QLR, des mod\u00e8les d&rsquo;impression, des mod\u00e8les de traitement et des scripts Python dans le navigateur<\/span><\/span>:<\/h5>\n<div style=\"width: 576px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-12\" width=\"576\" height=\"540\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/qlr.mp4?_=12\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/qlr.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/qlr.mp4<\/a><\/video><\/div>\n<h5><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">Nouvelle barre de recherche \u00ab\u00a0locator\u00a0\u00bb,\u00a0 permettant un acc\u00e8s rapide aux calques, aux fonctionnalit\u00e9s, aux actions, aux algorithmes:<\/span><\/span><\/h5>\n<div style=\"width: 476px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-13\" width=\"476\" height=\"438\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/locator.mp4?_=13\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/locator.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/locator.mp4<\/a><\/video><\/div>\n<h5><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">Reprojection automatique des calques dans les algorithmes de traitement (plus besoin de cr\u00e9er des calques temporaires juste pour couper des calques dans un autre CRS):<\/span><\/span><\/h5>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-14\" width=\"640\" height=\"340\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/reprojection.mp4?_=14\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/reprojection.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/reprojection.mp4<\/a><\/video><\/div>\n<h5><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">Nouveaux widgets\u00a0 pour d\u00e9finir les polices et les symboles des \u00e9l\u00e9ments:<\/span><\/span><\/h5>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-15\" width=\"640\" height=\"340\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/elements.mp4?_=15\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/elements.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/elements.mp4<\/a><\/video><\/div>\n<h5><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">Des vues de cartes 3D interactives et enti\u00e8rement int\u00e9gr\u00e9es:<\/span><\/span><\/h5>\n<div style=\"width: 352px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-16\" width=\"352\" height=\"370\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/3D.mp4?_=16\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/3D.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/3D.mp4<\/a><\/video><\/div>\n<h5><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">Mise \u00e0 jour automatique des valeurs de champ chaque fois qu&rsquo;une entit\u00e9 est modifi\u00e9e:<\/span><\/span><\/h5>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-17\" width=\"640\" height=\"429\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/autoupdate.mp4?_=17\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/autoupdate.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/autoupdate.mp4<\/a><\/video><\/div>\n<h5><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">Valeurs des param\u00e8tres \u00ab\u00a0Donn\u00e9es d\u00e9finies\u00a0\u00bb pour les param\u00e8tres de traitement (<\/span> <span class=\"\">Par exemple:<\/span> <span class=\"\">fonction de tampon <\/span><\/span><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">bas\u00e9e <\/span><\/span><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">sur une expression) :<\/span><\/span><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><\/span><\/h5>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-4896-18\" width=\"640\" height=\"416\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/expression.mp4?_=18\" \/><a href=\"http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/expression.mp4\">http:\/\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/02\/expression.mp4<\/a><\/video><\/div>\n<p><span id=\"result_box\" class=\"\" lang=\"fr\" tabindex=\"-1\"><span class=\"\">\u00a0<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nouvelle version de QGis est disponible depuis le 23 f\u00e9vrier 2018. Petit rappel des raisons de cette nouvelle mouture:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[425,62],"tags":[1416,58],"class_list":["post-4896","post","type-post","status-publish","format-standard","hentry","category-non-classe-fr","category-qgis-2","tag-3-0","tag-qgis"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p6XU0A-1gY","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/4896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/comments?post=4896"}],"version-history":[{"count":0,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/4896\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/media?parent=4896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/categories?post=4896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/tags?post=4896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}