﻿{"id":7106,"date":"2018-11-20T08:47:24","date_gmt":"2018-11-20T07:47:24","guid":{"rendered":"http:\/\/www.sigterritoires.fr\/?p=7106"},"modified":"2018-12-03T14:39:55","modified_gmt":"2018-12-03T13:39:55","slug":"tutoriel-classification-dimages-avec-qgis-1-introduction","status":"publish","type":"post","link":"https:\/\/www.sigterritoires.fr\/index.php\/tutoriel-classification-dimages-avec-qgis-1-introduction\/","title":{"rendered":"Tutoriel classification d&rsquo;images avec QGis: 1- Introduction"},"content":{"rendered":"\n<p>Tout d&rsquo;abord, un avertissement: ce tutoriel ne s&rsquo;adresse pas aux utilisateurs dont le traitement d&rsquo;images spatiales est leur m\u00e9tier. Il s&rsquo;adresse aux utilisateurs de <a href=\"https:\/\/www.sigterritoires.fr\/\">SIG<\/a> qui doivent se lancer dans le traitement d&rsquo;images dans le but d&rsquo;enrichir leur donn\u00e9es. Le but est d&rsquo;aplanir les \u00e9cueils du d\u00e9butant et de fournir quelques bases th\u00e9oriques pour ne pas simplement suivre une recette de cuisine. Les aspects th\u00e9oriques ne sont donc pas exhaustifs et on se permettra quelques approximations pour ne pas rendre le discours incompr\u00e9hensible pour le n\u00e9ophyte.<\/p>\n\n\n\n<p>Une grande partie des explications est tir\u00e9e de l&rsquo;excellent site de <a href=\"https:\/\/www.rncan.gc.ca\/accueil\">Ressources naturelles Canada<\/a>, auxquelles nous avons ajout\u00e9 toute la partie pratique avec QGis.&nbsp; Vous trouverez le m\u00eame tutoriel mais adapt\u00e9 aux outils propos\u00e9 par ArcGis sur notre site.<\/p>\n\n\n\n<p>Parmi la grande vari\u00e9t\u00e9 d&rsquo;outil propos\u00e9s par QGis pour r\u00e9aliser le travail de classification d&rsquo;images, nous utiliserons dans ce tutoriel:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>le plug-in SEMI AUTOMATIC CLASSIFICATION<\/li><li>les outils de traitement de QGis<\/li><\/ul>\n\n\n\n<p>Le plug-in SEMI AUTOMATIC CLASSIFICATION est tellement performant que l&rsquo;on pourrait se contenter de&nbsp; lui pour l&rsquo;ensemble du tutoriel. Mais dans ce cas il serait un bo\u00eete noire et vous ne sauriez pas faire ce qu&rsquo;il fait. Nous verrons donc comment faire les diff\u00e9rentes op\u00e9rations sans utiliser le plugin (par exemple la correction atmosph\u00e9rique) et apr\u00e8s, nous verrons comment gagner du temps avec l&rsquo;utilisation du plugin (en cochant une case pour la correction atmosph\u00e9rique!).<\/p>\n\n\n\n<p>Nous donnerons la marche \u00e0 suivre pour les versions 2.18 et 3.4 de QGis.<\/p>\n\n\n\n<p>Le tutoriel abordera les trois grandes phases du travail de classification d&rsquo;images:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>le pr\u00e9traitement et l\u2019exploration des donn\u00e9es<\/li><li>la classification d&rsquo;images \u00e0 proprement parler<\/li><li>le post-traitement des classifications<\/li><\/ul>\n\n\n\n<p><!--more--><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1- Introduction<\/h2>\n\n\n\n<p>&nbsp;L&rsquo;interpr\u00e9tation et l&rsquo;analyse de l&rsquo;imagerie de t\u00e9l\u00e9d\u00e9tection ont pour but d&rsquo;identifier et de mesurer diff\u00e9rentes cibles dans une image pour pouvoir en extraire l&rsquo;information utile. En t\u00e9l\u00e9d\u00e9tection, une cible est d\u00e9finie comme \u00e9tant toute structure ou objet observable dans une image. Les cibles peuvent \u00eatre des points, des lignes ou des surfaces. Elles peuvent donc pr\u00e9senter des formes vari\u00e9es mais elles doivent obligatoirement r\u00e9pondre \u00e0 une caract\u00e9ristique:&nbsp; elles doivent \u00eatre distinctives, c&rsquo;est \u00e0 dire qu&rsquo;elles doivent contraster avec les structures avoisinantes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La photo-interpr\u00e9tation<\/h2>\n\n\n\n<p>L&rsquo;interpr\u00e9tation et l&rsquo;identification des cibles en t\u00e9l\u00e9d\u00e9tection peuvent \u00eatre&nbsp; faites de fa\u00e7on visuelle, c&rsquo;est-\u00e0-dire par un interpr\u00e8te humain. Dans ce cas,&nbsp; l&rsquo;imagerie est pr\u00e9sent\u00e9e dans un format photographique, ind\u00e9pendamment du type de capteurs et de la mani\u00e8re dont les donn\u00e9es sont acquises.<\/p>\n\n\n\n<p>L&rsquo;interpr\u00e9tation et l&rsquo;analyse visuelles datent du tout d\u00e9but de la t\u00e9l\u00e9d\u00e9tection avec l&rsquo;interpr\u00e9tation de photos a\u00e9riennes. L&rsquo;interpr\u00e9tation visuelle est souvent limit\u00e9e \u00e0 un seul canal de donn\u00e9es ou une seule image \u00e0 la fois, en raison de la difficult\u00e9 d&rsquo;effectuer une interpr\u00e9tation visuelle avec plusieurs images. L&rsquo;interpr\u00e9tation humaine est un proc\u00e9d\u00e9 subjectif, ce qui veut dire que les r\u00e9sultats peuvent varier d&rsquo;un interpr\u00e8te \u00e0 l&rsquo;autre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La classification d&rsquo;image<\/h2>\n\n\n\n<p>Un analyste qui tente de classer les caract\u00e9ristiques d&rsquo;une image, utilise les \u00e9l\u00e9ments de l&rsquo;interpr\u00e9tation visuelle (photo-interpr\u00e9tation) pour identifier des groupes homog\u00e8nes de pixels qui repr\u00e9sentent des classes int\u00e9ressantes de surfaces. La classification num\u00e9rique des images utilise l&rsquo;information spectrale contenue dans les valeurs d&rsquo;une ou de plusieurs bandes spectrales pour classifier chaque pixel individuellement. Ce type de classification est appel\u00e9 reconnaissance de regroupements spectraux. Les deux fa\u00e7ons de proc\u00e9der (manuelle ou automatique) ont pour but d&rsquo;assigner une classe particuli\u00e8re ou th\u00e8me (par exemple : eau, for\u00eat de conif\u00e8res, ma\u00efs, bl\u00e9, etc.) \u00e0 chacun des pixels d&rsquo;une image. La \u00ab\u00a0nouvelle\u00a0\u00bb image qui repr\u00e9sente la classification est compos\u00e9e d&rsquo;une mosa\u00efque de pixels qui appartiennent chacun \u00e0 un th\u00e8me particulier. Cette image est essentiellement une repr\u00e9sentation th\u00e9matique de l&rsquo;image originale.<\/p>\n\n\n\n<p>Lorsqu&rsquo;on parle de classes, il faut faire la distinction entre des <strong>classes d&rsquo;information<\/strong> et des <strong>classes spectrales<\/strong>. Les classes d&rsquo;information sont des cat\u00e9gories d&rsquo;int\u00e9r\u00eat que l&rsquo;analyste tente d&rsquo;identifier dans les images, comme diff\u00e9rents types de cultures, de for\u00eats ou d&rsquo;esp\u00e8ce d&rsquo;arbres, diff\u00e9rents types de caract\u00e9ristiques g\u00e9ologiques ou de roches, etc. Les classes spectrales sont des groupes de pixels qui ont les m\u00eames caract\u00e9ristiques (ou presque) en ce qui a trait \u00e0 leur valeur d&rsquo;intensit\u00e9 dans les diff\u00e9rentes bandes spectrales des donn\u00e9es. L&rsquo;objectif ultime de la classification est de faire la correspondance entre les classes spectrales et les classes d&rsquo;information. Il est rare qu&rsquo;une correspondance directe soit possible entre ces deux types de classes. Des classes spectrales bien d\u00e9finies peuvent appara\u00eetre parfois sans qu&rsquo;elles correspondent n\u00e9cessairement \u00e0 des classes d&rsquo;information int\u00e9ressantes pour l&rsquo;analyse. D&rsquo;un autre c\u00f4t\u00e9, une classe d&rsquo;information tr\u00e8s large (par exemple la for\u00eat) peut contenir plusieurs sous-classes spectrales avec des variations spectrales d\u00e9finies. En utilisant l&rsquo;exemple de la for\u00eat, les sous-classes spectrales peuvent \u00eatre caus\u00e9es par des variations dans l&rsquo;\u00e2ge, l&rsquo;esp\u00e8ce, la densit\u00e9 des arbres ou simplement par les effets d&rsquo;ombrage ou des variations dans l&rsquo;illumination. L&rsquo;analyste a le r\u00f4le de d\u00e9terminer de l&rsquo;utilit\u00e9 des diff\u00e9rentes classes spectrales et de valider leur correspondance \u00e0 des classes d&rsquo;informations utiles.<\/p>\n\n\n\n<p>Les m\u00e9thodes de classification les plus communes peuvent \u00eatre s\u00e9par\u00e9es en deux grandes cat\u00e9gories : les m\u00e9thodes de <strong>classification supervis\u00e9e<\/strong> et les m\u00e9thodes de <strong>classification non supervis\u00e9e<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Classification supervis\u00e9e<\/h2>\n\n\n\n<p>Lors de l&rsquo;utilisation d&rsquo;une m\u00e9thode de classification supervis\u00e9e, l&rsquo;analyste identifie des \u00e9chantillons assez homog\u00e8nes de l&rsquo;image qui sont repr\u00e9sentatifs de diff\u00e9rents types de surfaces (classes d&rsquo;information). Ces \u00e9chantillons forment un ensemble de donn\u00e9es-tests. La s\u00e9lection de ces donn\u00e9es-tests est bas\u00e9e sur les connaissances de l&rsquo;analyste, sa familiarit\u00e9 avec les r\u00e9gions g\u00e9ographiques et les types de surfaces pr\u00e9sents dans l&rsquo;image. L&rsquo;analyste supervise donc la classification d&rsquo;un ensemble sp\u00e9cifique de classes. Les informations num\u00e9riques pour chacune des bandes et pour chaque pixel de ces ensembles sont utilis\u00e9es pour que l&rsquo;ordinateur puisse d\u00e9finir les classes et ensuite reconna\u00eetre des r\u00e9gions aux propri\u00e9t\u00e9s similaires \u00e0 chaque classe. L&rsquo;ordinateur utilise un programme sp\u00e9cial ou algorithme afin de d\u00e9terminer la \u00ab\u00a0signature\u00a0\u00bb num\u00e9rique de chacune des classes. Plusieurs algorithmes diff\u00e9rents sont possibles. Une fois que l&rsquo;ordinateur a \u00e9tabli la signature spectrale de chaque classe, il assigne&nbsp; chaque pixel de l&rsquo;image \u00e0 la classe avec laquelle il a le plus d&rsquo;affinit\u00e9s.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Une classification supervis\u00e9e commence donc par l&rsquo;identification des classes d&rsquo;information qui sont ensuite utilis\u00e9es pour d\u00e9finir les classes spectrales qui les repr\u00e9sentent.<\/p><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Classification non supervis\u00e9e<\/h2>\n\n\n\n<p>La classification non supervis\u00e9e proc\u00e8de de fa\u00e7on contraire. Les classes spectrales sont form\u00e9es en premier, bas\u00e9es sur l&rsquo;information num\u00e9rique des donn\u00e9es seulement. Ces classes sont ensuite associ\u00e9es, par un analyste, \u00e0 des classes d&rsquo;information utile (si possible). Des programmes appel\u00e9s algorithmes de classification sont utilis\u00e9s pour d\u00e9terminer les groupes statistiques naturels ou les structures des donn\u00e9es. Habituellement, l&rsquo;analyste sp\u00e9cifie le nombre de groupes ou classes qui seront form\u00e9s avec les donn\u00e9es. De plus, l&rsquo;analyste peut sp\u00e9cifier certains param\u00e8tres relatifs \u00e0 la distance entre les classes et la variance \u00e0 l&rsquo;int\u00e9rieur m\u00eame d&rsquo;une classe. Le r\u00e9sultat final de ce processus de classification it\u00e9ratif peut cr\u00e9er des classes que l&rsquo;analyste voudra combiner, ou des classes qui devraient \u00eatre s\u00e9par\u00e9es de nouveau. Chacune de ces \u00e9tapes n\u00e9cessite une nouvelle application de l&rsquo;algorithme. L&rsquo;intervention humaine n&rsquo;est donc pas totalement exempte de la classification non supervis\u00e9e. Cependant<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>cette m\u00e9thode ne commence pas avec un ensemble pr\u00e9d\u00e9termin\u00e9 de classes comme pour la classification supervis\u00e9e.<\/p><\/blockquote><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">L&rsquo;interpr\u00e9tation visuelle<\/h2>\n\n\n\n<p>La reconnaissance des cibles est la cl\u00e9 de l&rsquo;interpr\u00e9tation et de l&rsquo;extraction d&rsquo;information. L&rsquo;observation des diff\u00e9rences entre les cibles et leurs arri\u00e8re-plans implique la comparaison entre diff\u00e9rentes cibles en se basant sur une combinaison de sept caract\u00e9ristiques : <strong>ton, forme, taille, patron, texture, ombre<\/strong> et <strong>association<\/strong>. Consciemment ou non, nous utilisons r\u00e9guli\u00e8rement ces caract\u00e9ristiques pour les interpr\u00e9tations visuelles que nous effectuons quotidiennement. L&rsquo;identification des cibles en t\u00e9l\u00e9d\u00e9tection bas\u00e9e sur les sept caract\u00e9ristiques visuelles nous permet de mieux interpr\u00e9ter et analyser.<\/p>\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6934\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/tutoriel-classification-dimages-avec-arcmap-1-introduction\/ton\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/ton.jpg?fit=235%2C225&amp;ssl=1\" data-orig-size=\"235,225\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ton\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/ton.jpg?fit=235%2C225&amp;ssl=1\" class=\"alignleft wp-image-6934\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/ton.jpg?resize=225%2C215&#038;ssl=1\" alt=\"\" width=\"225\" height=\"215\"><\/figure>\n<p><strong>Le ton<\/strong> r\u00e9f\u00e8re \u00e0 la clart\u00e9 relative ou la couleur (teinte) des objets dans une image. G\u00e9n\u00e9ralement, la nuance de ton est l&rsquo;\u00e9l\u00e9ment fondamental pour diff\u00e9rencier les cibles et les structures. Les variations de ton permettent aussi la diff\u00e9renciation des formes, textures et patrons des objets.<\/p>\n<p>&nbsp;<\/p>\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6952\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/tutoriel-classification-dimages-avec-arcmap-1-introduction\/shape-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/shape-2.jpg?fit=225%2C214&amp;ssl=1\" data-orig-size=\"225,214\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"shape\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/shape-2.jpg?fit=225%2C214&amp;ssl=1\" class=\"alignleft wp-image-6952\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/shape-2.jpg?resize=225%2C214&#038;ssl=1\" alt=\"\" width=\"225\" height=\"214\"><\/figure>\n<p><strong>La forme<\/strong> r\u00e9f\u00e8re \u00e0 l&rsquo;allure g\u00e9n\u00e9rale, la structure ou le contour des objets pris individuellement. La forme peut \u00eatre un indice tr\u00e8s important pour l&rsquo;interpr\u00e9tation. Les formes aux bordures rectilignes se retrouvent g\u00e9n\u00e9ralement dans les r\u00e9gions urbaines ou sont des champs agricoles, alors que les structures naturelles, telles que les bordures des for\u00eats, sont g\u00e9n\u00e9ralement plus irr\u00e9guli\u00e8res, sauf dans les endroits o\u00f9 l&rsquo;homme a construit une route ou effectu\u00e9 une coupe \u00e0 blanc. Les fermes o\u00f9 les champs de culture irrigu\u00e9s par des syst\u00e8mes d&rsquo;arrosage automatiques pr\u00e9sentent des formes circulaires.<\/p>\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6953\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/tutoriel-classification-dimages-avec-arcmap-1-introduction\/size-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/size-2.jpg?fit=251%2C230&amp;ssl=1\" data-orig-size=\"251,230\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"size\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/size-2.jpg?fit=251%2C230&amp;ssl=1\" class=\"alignleft wp-image-6953\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/size-2.jpg?resize=225%2C206&#038;ssl=1\" alt=\"\" width=\"225\" height=\"206\"><\/figure>\n<p><strong>La taille<\/strong> d&rsquo;un objet sur une image est fonction de l&rsquo;\u00e9chelle. Il est important d&rsquo;\u00e9valuer la taille d&rsquo;une cible par rapport aux autres objets dans une sc\u00e8ne (taille relative), ainsi que la taille absolue, afin d&rsquo;aider l&rsquo;interpr\u00e9tation de cette cible. Une \u00e9valuation rapide de la taille approximative d&rsquo;une cible facilite souvent l&rsquo;interpr\u00e9tation. Par exemple, dans une image o\u00f9 l&rsquo;on aurait \u00e0 distinguer diff\u00e9rentes zones d&rsquo;utilisation du sol et \u00e0 identifier une aire comportant des b\u00e2timents, les grosses structures telles que les usines ou les entrep\u00f4ts sugg\u00e9reraient des propri\u00e9t\u00e9s commerciales, tandis que de plus petits \u00e9l\u00e9ments sugg\u00e9reraient des lieux r\u00e9sidentiels.<\/p>\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6950\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/tutoriel-classification-dimages-avec-arcmap-1-introduction\/pattern-4\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/pattern-3.jpg?fit=122%2C120&amp;ssl=1\" data-orig-size=\"122,120\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"pattern\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/pattern-3.jpg?fit=122%2C120&amp;ssl=1\" class=\"alignleft wp-image-6950\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/pattern-3.jpg?resize=225%2C221&#038;ssl=1\" alt=\"\" width=\"225\" height=\"221\"><\/figure>\n<p><strong>Le patron<\/strong> r\u00e9f\u00e8re \u00e0 l&rsquo;agencement spatial des objets visiblement discernables. Une r\u00e9p\u00e9tition ordonn\u00e9e de tons similaires et de textures produit un patron distinctif et facilement reconnaissable. Les vergers avec leurs arbres r\u00e9guli\u00e8rement dispos\u00e9s, ou les rues r\u00e9guli\u00e8rement bord\u00e9es de maisons sont de bons exemples de patrons.<\/p>\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6954\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/tutoriel-classification-dimages-avec-arcmap-1-introduction\/texture-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/texture-2.jpg?fit=120%2C120&amp;ssl=1\" data-orig-size=\"120,120\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"texture\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/texture-2.jpg?fit=120%2C120&amp;ssl=1\" class=\"wp-image-6954 alignleft\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/texture-2.jpg?resize=225%2C221&#038;ssl=1\" alt=\"\" width=\"225\" height=\"221\"><\/figure>\n<p><strong>La texture<\/strong> r\u00e9f\u00e8re \u00e0 l&rsquo;arrangement et \u00e0 la fr\u00e9quence des variations de teintes dans des r\u00e9gions particuli\u00e8res d&rsquo;une image. Des textures rugueuses consisteraient en des tons en rayures o\u00f9 les niveaux de gris changent brusquement dans une petite r\u00e9gion, alors que les textures lisses auraient peu ou pas de variations de tons. Les textures lisses sont souvent le r\u00e9sultat de surfaces uniformes telles que des champs, du pavement ou des terrains gazonn\u00e9s. Une cible avec une surface rugueuse et une structure irr\u00e9guli\u00e8re, telle qu&rsquo;une for\u00eat, r\u00e9sulte en une texture d&rsquo;apparence rugueuse. La texture est l&rsquo;un des \u00e9l\u00e9ments les plus importants pour diff\u00e9rencier les structures sur une image radar.<\/p>\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6951\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/tutoriel-classification-dimages-avec-arcmap-1-introduction\/shadow-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/shadow-2.jpg?fit=120%2C120&amp;ssl=1\" data-orig-size=\"120,120\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"shadow\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/shadow-2.jpg?fit=120%2C120&amp;ssl=1\" class=\"wp-image-6951 alignleft\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/shadow-2.jpg?resize=225%2C221&#038;ssl=1\" alt=\"\" width=\"225\" height=\"221\"><\/figure>\n<p><strong>Les ombres<\/strong> sont aussi utiles pour l&rsquo;interpr\u00e9tation puisqu&rsquo;elles donnent une id\u00e9e du profil et de la hauteur relative des cibles pouvant \u00eatre identifi\u00e9es facilement. Les ombres peuvent cependant r\u00e9duire, voire \u00e9liminer l&rsquo;interpr\u00e9tation dans leur entourage, puisque les cibles situ\u00e9es dans les ombres sont moins, ou pas du tout discernables. En imagerie radar, les ombres sont particuli\u00e8rement utiles pour rehausser ou identifier la topographie et les formes g\u00e9ologiques, particuli\u00e8rement en imagerie radar.<\/p>\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6937\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/tutoriel-classification-dimages-avec-arcmap-1-introduction\/assoc\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/assoc.jpg?fit=120%2C120&amp;ssl=1\" data-orig-size=\"120,120\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"assoc\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/assoc.jpg?fit=120%2C120&amp;ssl=1\" class=\"wp-image-6937 alignleft\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2018\/11\/assoc.jpg?resize=225%2C221&#038;ssl=1\" alt=\"\" width=\"225\" height=\"221\"><\/figure>\n<p><strong>L&rsquo;association<\/strong> tient compte de la relation entre la cible d&rsquo;int\u00e9r\u00eat et d&rsquo;autres objets ou structures reconnaissables qui sont \u00e0 proximit\u00e9. L&rsquo;identification d&rsquo;\u00e9l\u00e9ments qu&rsquo;on s&rsquo;attend normalement \u00e0 retrouver \u00e0 proximit\u00e9 d&rsquo;autres structures peut donner de l&rsquo;information facilitant l&rsquo;identification. Dans l&rsquo;exemple ci-dessous, les propri\u00e9t\u00e9s commerciales peuvent \u00eatre associ\u00e9es avec les routes \u00e0 proximit\u00e9, alors que les aires r\u00e9sidentielles seraient associ\u00e9es avec les \u00e9coles, les terrains de jeux et de sports. Dans notre exemple, un lac est associ\u00e9 \u00e0 des bateaux, \u00e0 une marina et \u00e0 un parc r\u00e9cr\u00e9atif tout pr\u00e8s.<\/p>\n<p>&nbsp;<\/p>\n\n\n<h2 class=\"wp-block-heading\">Le processus de classification d&rsquo;images<\/h2>\n\n\n\n<p>L&rsquo;ensemble du processus menant de l&rsquo;image brute acquise par satellite ou par avion \u00e0 une carte th\u00e9matique pr\u00e9sentant les entit\u00e9s g\u00e9ographiques choisies se d\u00e9compose en une s\u00e9rie d&rsquo;\u00e9tapes:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/wp.me\/p6XU0A-1QF\">Exploration des donn\u00e9es et pr\u00e9traitement<\/a><ul><li><a href=\"https:\/\/wp.me\/p6XU0A-1QF\">le pr\u00e9traitement des images<\/a><\/li><li><a href=\"https:\/\/wp.me\/p6XU0A-1QN\">correction atmosph\u00e9rique<\/a><\/li><li><a href=\"https:\/\/wp.me\/p6XU0A-1Tx\">le rehaussement de l&rsquo;image<\/a><\/li><li>les transformations de l&rsquo;image<\/li><\/ul><\/li><li>Classification de l&rsquo;image<ul><li>Collecte d&rsquo;\u00e9chantillons d&rsquo;apprentissage<\/li><li>\u00c9valuation d&rsquo;\u00e9chantillons d&rsquo;apprentissage<\/li><li>Mise \u00e0 jour des classes<\/li><li>Cr\u00e9ation du fichier de signatures<\/li><li>Agr\u00e9gation (classification non assist\u00e9e)<\/li><li>Examen du fichier de signatures<\/li><li>Modification du fichier de signatures<\/li><li>Application de la classification<\/li><\/ul><\/li><li>Traitements de post-classification<ul><li>Filtrage<\/li><li>Lissage<\/li><li>G\u00e9n\u00e9ralisation<\/li><\/ul><\/li><\/ul>\n\n\n\n<p>Nous aborderons dans les prochains articles chacun de ces th\u00e8mes. Au fur et \u00e0 mesure des publications, nous ajouterons les liens vers les articles correspondants.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tout d&rsquo;abord, un avertissement: ce tutoriel ne s&rsquo;adresse pas aux utilisateurs dont le traitement d&rsquo;images spatiales est leur m\u00e9tier. Il s&rsquo;adresse aux utilisateurs de SIG qui doivent se lancer dans le traitement d&rsquo;images dans le but&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[147,62],"tags":[1482,1480,1490,1484,1488,58,1492,1486],"class_list":["post-7106","post","type-post","status-publish","format-standard","hentry","category-images","category-qgis-2","tag-assistee","tag-classification","tag-image","tag-non-assistee","tag-non-supervisee","tag-qgis","tag-semi-automatic-classification","tag-supervisee"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p6XU0A-1QC","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/7106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/comments?post=7106"}],"version-history":[{"count":0,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/7106\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/media?parent=7106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/categories?post=7106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/tags?post=7106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}