﻿{"id":7766,"date":"2019-01-11T03:11:34","date_gmt":"2019-01-11T02:11:34","guid":{"rendered":"http:\/\/www.sigterritoires.fr\/?p=7766"},"modified":"2023-06-24T23:06:52","modified_gmt":"2023-06-24T21:06:52","slug":"qfield-el-dispositivo-movil-de-qgis-para-android","status":"publish","type":"post","link":"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/","title":{"rendered":"QField : el dispositivo m\u00f3vil de QGis para Android"},"content":{"rendered":"\n<p>QField &nbsp;permite realizar trabajos\nde campo en proyectos QGis con tel\u00e9fonos o tabletas Android. <br>\nEn este art\u00edculo analizaremos c\u00f3mo instalar QField en un dispositivo m\u00f3vil y\nc\u00f3mo instalar y trabajar en un proyecto de QGis. <br>\nVeamos qu\u00e9 es posible hacer con QField ? <br>\nQField permite instalar un proyecto QGis en su tel\u00e9fono o tableta. Obtendr\u00e1 una\npantalla equivalente a la pantalla QGis de su PC y podr\u00e1 editar el atributo o\nla informaci\u00f3n geom\u00e9trica en el campo. No confunda QField con la versi\u00f3n Android\nde QGis. QField abre una interfaz equivalente a la que tiene en su PC, con\ntodas las caracter\u00edsticas de QGis. QField abre una interfaz simplificada en la\nque podr\u00e1, principalmente, &nbsp;actualizar\nlos datos incluidos en su proyecto. <\/p>\n\n\n\n<!--more-->\n\n\n\n<p><strong>Descarga<\/strong> <strong>QField<\/strong> <strong>a tu dispositivo m\u00f3vil.<\/strong> \n\nHay varias formas de descargar QField : a trav\u00e9s\nde Play Store, la p\u00e1gina de descargas de QGis, o simplemente buscando en su navegador\ncon las palabras \u00ab\u00a0qgis android\u00a0\u00bb: &nbsp;&nbsp;\n\n\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" data-attachment-id=\"7767\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/111-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/111.png?fit=525%2C328&amp;ssl=1\" data-orig-size=\"525,328\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"111\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/111.png?fit=525%2C328&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/111.png?resize=525%2C328&#038;ssl=1\" alt=\"\" class=\"wp-image-7767\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/111.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/111.png?resize=300%2C187&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nSeleccione\nla opci\u00f3n QField para QGis Experimental (no QGis Experimental) &nbsp;&nbsp;\n\n\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" data-attachment-id=\"7768\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/112-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/112.png?fit=525%2C328&amp;ssl=1\" data-orig-size=\"525,328\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"112\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/112.png?fit=525%2C328&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/112.png?resize=525%2C328&#038;ssl=1\" alt=\"\" class=\"wp-image-7768\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/112.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/112.png?resize=300%2C187&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nLuego,\nseleccione Instalar &nbsp;&nbsp;\n\n\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" data-attachment-id=\"7769\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/113-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/113.png?fit=525%2C328&amp;ssl=1\" data-orig-size=\"525,328\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"113\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/113.png?fit=525%2C328&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/113.png?resize=525%2C328&#038;ssl=1\" alt=\"\" class=\"wp-image-7769\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/113.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/113.png?resize=300%2C187&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nSeleccione,\nnuevamente, Instalar para permitir que la aplicaci\u00f3n acceda a los datos.<br>\nCuando haya terminado, cierre la ventana de Play Store y seleccione el icono de\nQField que acaba de agregarse a su escritorio: &nbsp;&nbsp;\n\n\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" data-attachment-id=\"7770\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/114-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/114.png?fit=525%2C328&amp;ssl=1\" data-orig-size=\"525,328\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"114\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/114.png?fit=525%2C328&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/114.png?resize=525%2C328&#038;ssl=1\" alt=\"\" class=\"wp-image-7770\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/114.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/114.png?resize=300%2C187&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nUna\nventana le informa que los diferentes m\u00f3dulos est\u00e1n siendo instalados. &nbsp;&nbsp;\n\n\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"250\" data-attachment-id=\"7771\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/115-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/115.png?fit=525%2C250&amp;ssl=1\" data-orig-size=\"525,250\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"115\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/115.png?fit=525%2C250&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/115.png?resize=525%2C250&#038;ssl=1\" alt=\"\" class=\"wp-image-7771\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/115.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/115.png?resize=300%2C143&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p>Luego, una ventana le muestra que la instalaci\u00f3n ha sido completada y pronta\npara ser utilizada: <\/p>\n\n\n\n<p>Como lo indica el mensaje, ahora necesita crear un proyecto en la\nversi\u00f3n de QGis de su PC, transferirlo a su dispositivo m\u00f3vil y abrirlo usando\nel bot\u00f3n de esta p\u00e1gina. <\/p>\n\n\n\n<p><strong>C\u00f3mo crear un proyecto QGis?<\/strong> \n\nDebe crear un proyecto en su PC con QGis. Obtendr\u00e1a\nun archivo .qgs que deber\u00e1 transferir a su m\u00f3vil. Pero tambi\u00e9n deber\u00e1\ntransferir los datos requeridos por su proyecto. Veamos un ejemplo:\n\n\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"286\" data-attachment-id=\"7772\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/attachment\/116\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/116.png?fit=525%2C286&amp;ssl=1\" data-orig-size=\"525,286\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"116\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/116.png?fit=525%2C286&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/116.png?resize=525%2C286&#038;ssl=1\" alt=\"\" class=\"wp-image-7772\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/116.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/116.png?resize=300%2C163&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p><strong>Crear un directorio con todos los archivos que\nnecesita el proyecto.<\/strong> <\/p>\n\n\n\n<p>Todos los datos requeridos deben estar f\u00edsicamente en tu m\u00f3vil. WFS,\nconecciones WMS, concciones de internet como OSM, etc., no funcionar\u00e1n. <br>\nEn nuestro ejemplo, usamos OpenStreetMap como mapa de fondo. Para poder\nutilizarlo en nuestro dispositivo m\u00f3vil, debemos guardar el mapa de fondo como\nuna imagen y luego cargarlo en nuestro proyecto en lugar de en la capa OSM. <br>\nPara las capas WFS, WMS, etc., tambi\u00e9n tenemos que guardar la capa como un\narchivo shp y reemplazar las capas con sus archivos en nuestro proyecto. <br>\nEn nuestro ejemplo, creamos un directorio \u00ab\u00a0Campus\u00a0\u00bb donde guardamos la\nimagen de OSM y el archivo con los datos de los edificios. Guardamos el\nproyecto en este directorio. <\/p>\n\n\n\n<p><strong>Crear la simbolog\u00eda deseada para el trabajo de\ncampo.<\/strong> <\/p>\n\n\n\n<p>Para cada capa, puede utilizar todas las funciones de QGis relativas a\nsimbolog\u00eda y etiquetado. No podr\u00e1 cambiar esta configuraci\u00f3n en QField . <\/p>\n\n\n\n<p><strong>Transferencia del proyecto a su m\u00f3vil<\/strong> \n\nConecte su tel\u00e9fono m\u00f3vil a su PC y copie el\ndirectorio junto con su proyecto y datos. Si bien puede hacerlo en cualquier\nlugar, deber\u00eda hacerlo en el directorio de Android \/ Datos &nbsp;\n\n\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"229\" data-attachment-id=\"7773\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/attachment\/117\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/117.png?fit=525%2C229&amp;ssl=1\" data-orig-size=\"525,229\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"117\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/117.png?fit=525%2C229&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/117.png?resize=525%2C229&#038;ssl=1\" alt=\"\" class=\"wp-image-7773\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/117.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/117.png?resize=300%2C131&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p><strong>Iniciar<\/strong> <strong>QField<\/strong> <strong>en su m\u00f3vil<\/strong> \n\nInicie QField desde su escritorio m\u00f3vil. Tendr\u00e1\nuna ventana para seleccionar el proyecto, use el bot\u00f3n para navegar por los\narchivos &nbsp;&nbsp;\n\n\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" data-attachment-id=\"7774\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/attachment\/118\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/118.png?fit=525%2C328&amp;ssl=1\" data-orig-size=\"525,328\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"118\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/118.png?fit=525%2C328&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/118.png?resize=525%2C328&#038;ssl=1\" alt=\"\" class=\"wp-image-7774\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/118.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/118.png?resize=300%2C187&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nNavegue\npor los directorios, en nuestro ejemplo Android \/ Data \/ Campus, seleccione los\nproyectos en los archivo .qgs y haga clic en abrir. \n\n\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" data-attachment-id=\"7775\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/attachment\/119\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/119.png?fit=525%2C328&amp;ssl=1\" data-orig-size=\"525,328\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"119\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/119.png?fit=525%2C328&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/119.png?resize=525%2C328&#038;ssl=1\" alt=\"\" class=\"wp-image-7775\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/119.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/119.png?resize=300%2C187&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nQField\nabre la ventana del proyecto en su m\u00f3vil. &nbsp;&nbsp;\n\n\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" data-attachment-id=\"7776\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/attachment\/1110\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1110.png?fit=525%2C328&amp;ssl=1\" data-orig-size=\"525,328\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1110\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1110.png?fit=525%2C328&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1110.png?resize=525%2C328&#038;ssl=1\" alt=\"\" class=\"wp-image-7776\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1110.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1110.png?resize=300%2C187&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p>Hay dos botones en la parte superior izquierda. El bot\u00f3n azul le permite\nactivar la ubicaci\u00f3n de su m\u00f3vil y mostrar un punto rojo en el mapa que indica\nla posici\u00f3n geogr\u00e1fica del m\u00f3vil. \n\nEl bot\u00f3n de men\u00fa abre un panel: &nbsp;&nbsp;\n\n\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" data-attachment-id=\"7777\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/attachment\/1111\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1111.png?fit=525%2C328&amp;ssl=1\" data-orig-size=\"525,328\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1111\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1111.png?fit=525%2C328&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1111.png?resize=525%2C328&#038;ssl=1\" alt=\"\" class=\"wp-image-7777\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1111.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1111.png?resize=300%2C187&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nEn\nla parte superior del panel, hay dos botones. El primero (men\u00fa) cierra el\npanel. El segundo abre las opciones &nbsp;disponible: &nbsp;&nbsp;\n\n\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" data-attachment-id=\"7778\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/attachment\/1112\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1112.png?fit=525%2C328&amp;ssl=1\" data-orig-size=\"525,328\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1112\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1112.png?fit=525%2C328&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1112.png?resize=525%2C328&#038;ssl=1\" alt=\"\" class=\"wp-image-7778\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1112.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1112.png?resize=300%2C187&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nAdem\u00e1s\nde la opci\u00f3n Abrir un proyecto para cambiar de proyecto, la otra opci\u00f3n\nimportante es la opci\u00f3n Modo . &nbsp;&nbsp;\n\n\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" data-attachment-id=\"7779\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/attachment\/1113\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1113.png?fit=525%2C328&amp;ssl=1\" data-orig-size=\"525,328\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1113\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1113.png?fit=525%2C328&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1113.png?resize=525%2C328&#038;ssl=1\" alt=\"\" class=\"wp-image-7779\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1113.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1113.png?resize=300%2C187&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p>Existendos modalidades de trabajo: Navegar y Dibujar. <br>El primero se refiere a los atributos de las entidades, el segundo a las geometr\u00edas. <strong>Modo Navegaci\u00f3n<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" data-attachment-id=\"7780\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/attachment\/1114\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1114.png?fit=525%2C328&amp;ssl=1\" data-orig-size=\"525,328\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1114\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1114.png?fit=525%2C328&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1114.png?resize=525%2C328&#038;ssl=1\" alt=\"\" class=\"wp-image-7780\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1114.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1114.png?resize=300%2C187&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nEl\nmodo Navegaci\u00f3n permite seleccionar los identificadores de entidades en el\nbanner derecho toc\u00e1ndolos en el mapa. <br>\nSi toca el identificador del panel derecho, se abrir\u00e1 una nueva ventana con la\ntabla de atributos de la entidad: &nbsp;\n\n\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" data-attachment-id=\"7781\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/attachment\/1115\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1115.png?fit=525%2C328&amp;ssl=1\" data-orig-size=\"525,328\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1115\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1115.png?fit=525%2C328&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1115.png?resize=525%2C328&#038;ssl=1\" alt=\"\" class=\"wp-image-7781\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1115.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1115.png?resize=300%2C187&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p><strong>Modo Dibujar<\/strong> \n\nEn la parte superior derecha hay un l\u00e1piz para\neditar. Luego, puede ingresar \/ modificar los valores de los atributos. <br>\nEn el banner de la izquierda selecciona la capa a editar. El l\u00e1piz en la parte\ninferior izquierda entra en modo de edici\u00f3n. &nbsp;&nbsp;\n\n\n\n<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"328\" data-attachment-id=\"7782\" data-permalink=\"https:\/\/www.sigterritoires.fr\/index.php\/es\/qfield-el-dispositivo-movil-de-qgis-para-android\/attachment\/1116\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1116.png?fit=525%2C328&amp;ssl=1\" data-orig-size=\"525,328\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1116\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1116.png?fit=525%2C328&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1116.png?resize=525%2C328&#038;ssl=1\" alt=\"\" class=\"wp-image-7782\" srcset=\"https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1116.png?w=525&amp;ssl=1 525w, https:\/\/i0.wp.com\/www.sigterritoires.fr\/wp-content\/uploads\/2019\/01\/1116.png?resize=300%2C187&amp;ssl=1 300w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/figure>\n\n\n\n<p>El cursor est\u00e1 ubicado en el centro de la pantalla. A diferencia de la\nPC, se mueve el mapa en lugar del cursor. <br>\n\u2022 El bot\u00f3n + verde graba un nuevo punto. <br>\n\u2022 El bot\u00f3n X cancela la entidad y sale del modo de edici\u00f3n <br>\n\u2022 El bot\u00f3n &#8211; cancela el \u00faltimo punto introducido <br>\n\u2022 El bot\u00f3n amarillo completa la introducci\u00f3n de la entidad y la guarda, dejando\nel modo de edici\u00f3n. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>QField &nbsp;permite realizar trabajos de campo en proyectos QGis con tel\u00e9fonos o tabletas Android. En este art\u00edculo analizaremos c\u00f3mo instalar QField en un dispositivo m\u00f3vil y c\u00f3mo instalar y trabajar en un proyecto de QGis. Veamos&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[842],"tags":[],"class_list":["post-7766","post","type-post","status-publish","format-standard","hentry","category-non-classe-es"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p6XU0A-21g","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/7766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/comments?post=7766"}],"version-history":[{"count":0,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/posts\/7766\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/media?parent=7766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/categories?post=7766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sigterritoires.fr\/index.php\/wp-json\/wp\/v2\/tags?post=7766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}